{"id":9088,"date":"2022-03-10T10:08:56","date_gmt":"2022-03-10T09:08:56","guid":{"rendered":"https:\/\/www.iese.fraunhofer.de\/blog\/?p=9088"},"modified":"2025-08-19T11:42:55","modified_gmt":"2025-08-19T09:42:55","slug":"lebensmittelsicherheit","status":"publish","type":"post","link":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/","title":{"rendered":"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf"},"content":{"rendered":"<p class=\"lead\">Lebensmittelsicherheit geht uns alle an! \u2013 Klingt wie ein Werbeslogan, ist es aber nicht. Mehr denn je wird heute auf die Sicherheit unserer Nahrung geachtet. Und das ist auch gut so! Aber was passiert, wenn Lebensmittel einmal nicht sicher sind und zum Beispiel durch Schadstoffe oder Bakterien kontaminiert sind? Dann k\u00f6nnen gesundheitliche Sch\u00e4den f\u00fcr Konsument*innen, weitreichende Imagesch\u00e4den f\u00fcr die Lebensmittelhersteller und finanzielle Einbu\u00dfen die Folge sein. Das Thema hat also eine hohe Relevanz. In diesem Blog-Beitrag wollen wir darlegen, wie es mithilfe des sogenannten <a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/interview-crowdre-mit-der-crowd-marktpotenziale-von-softwareprodukten-heben\/\">CrowdRE<\/a> gelingen kann, Lebensmittelr\u00fcckrufe zu klassifizieren und somit R\u00fcckschl\u00fcsse auf etwaige Optimierungspotenziale innerhalb der Food Chain zu ziehen.<\/p>\n<p>Am <a href=\"https:\/\/www.iese.fraunhofer.de\/\">Fraunhofer IESE<\/a> forschen wir gemeinsam mit einer Reihe anderer Fraunhofer-Institute im Zusammenschluss der <a href=\"https:\/\/www.fcm.fraunhofer.de\">Fraunhofer-Allianz Ern\u00e4hrungswirtschaft<\/a> zu diversen Themen rund um \u00bbErn\u00e4hrung\u00ab. Dazu geh\u00f6ren u.a. Aspekte und Forschungsschwerpunkte wie Lebensmittelanalytik, Verpackungstechnologie, Sensorik, Produktionstechnik und Logistik sowie Landwirtschaft oder Digitalisierung entlang der gesamten Food Chain. Die ultimativen Ziele fokussieren dabei auf eine Steigerung der Lebensmittelqualit\u00e4t, eine Erm\u00f6glichung von Individualisierung und Food-Alternativen, die Gew\u00e4hrleistung von Lebensmittelsicherheit sowie die Unterst\u00fctzung von Nachhaltigkeit und Recycling.<\/p>\n<p>Insbesondere das Thema der \u00bbLebensmittelsicherheit\u00ab hat hohe Relevanz und geht uns alle an: Hersteller von Lebensmitteln, Konsument*innen mit ihrem t\u00e4glichen Bedarf und Beh\u00f6rden, die sich mit Lebensmitteln und Lebensmittelsicherheit besch\u00e4ftigen.<\/p>\n<p>Das <a href=\"https:\/\/www.bvl.bund.de\">Bundesamt f\u00fcr Verbraucherschutz und Lebensmittelsicherheit (BVL)<\/a> betreibt im Bereich Lebensmittelsicherheit das Portal <a href=\"https:\/\/www.lebensmittelwarnung.de\">Lebensmittelwarnung.de<\/a>, das Warnungen und R\u00fcckrufe in den Kategorien<\/p>\n<ul>\n<li>Lebensmittel,<\/li>\n<li>kosmetische Mittel wie z.B. zur Zahn-, Haut- oder Haarpflege,<\/li>\n<li>Bedarfsgegenst\u00e4nde wie z.B. Spielwaren, Schmuck, Gegenst\u00e4nde mit Lebensmittel- oder K\u00f6rperkontakt und<\/li>\n<li>T\u00e4towiermittel<\/li>\n<\/ul>\n<p>publiziert, nachdem die verantwortlichen Unternehmen den in ihrer Verantwortung liegenden R\u00fcckruf ver\u00f6ffentlicht haben. Gleichzeitig werden diese R\u00fcckrufe \u00fcber die <a href=\"https:\/\/twitter.com\/BVL_Bund\">Social-Media-Kan\u00e4le des BVL<\/a> und die <a href=\"https:\/\/twitter.com\/LMWarnung\">zugeh\u00f6rigen Kan\u00e4le der Website lebensmittelwarnung.de<\/a> (z. B. Twitter) bekannt gemacht.<\/p>\n<h3><strong>Eine Analyse der BVL Tweets mittels Crowd Requirements Engineering<\/strong><\/h3>\n<p>Als <a href=\"https:\/\/www.iese.fraunhofer.de\/\">Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering IESE<\/a> sind wir das Institut in der Fraunhofer-Allianz Ern\u00e4hrungswirtschaft, welches sich im Schwerpunkt mit Digitalisierung und digitalen Gesch\u00e4ftsmodellen besch\u00e4ftigt. Zum breiten Portfolio des IESE geh\u00f6rt auch das sogenannte <a href=\"https:\/\/www.iese.fraunhofer.de\/de\/leistungen\/requirements-engineering\/digitale-transformation.html\">Crowd Requirements Engineering (CrowdRE)<\/a>. CrowdRE erm\u00f6glicht eine automatisierte und anonymisierte Feedback- und Bewertungssammlung aus digitalen Quellen. Davon ausgehend lassen sich die dabei erhaltenen Informationen nach Aspekten wie positiven und negativen Anmerkungen oder auch gew\u00fcnschten Qualit\u00e4tseigenschaften oder weiteren Informationen analysieren. Als m\u00f6gliche Quellen dienen dabei z. B. Bewertungen aus Online Stores, Bewertungen von Apps in App Stores oder Social Media Postings wie z.B. Twitter Tweets. Das Fraunhofer IESE setzt CrowdRE bereits f\u00fcr eine Reihe diverser Unternehmen erfolgreich ein. Dazu geh\u00f6rt unter anderem auch die <a href=\"https:\/\/www.debeka.de\">Debeka Versicherung<\/a>, die Feedback von Nutzer*innen zu ihren Apps so zur gezielten Weiterentwicklung und Verbesserung nutzt. Die genannten Vorteile machen deutlich, welch gro\u00dfen Nutzen Unternehmen aus der CrowdRE-Technologie ziehen k\u00f6nnen. Mit Blick auf das Thema \u00bbLebensmittelsicherheit\u00ab lohnt es sich daher ebenfalls, einen genaueren Blick auf die vorhandenen Tweets mit Lebensmittelr\u00fcckrufen zu werfen. Gegenstand der Betrachtung waren dabei die R\u00fcckruf-Tweets des BVL der letzten beiden Kalenderjahre (2020 und 2021).<\/p>\n<div class=\"info-box\">\n<p><strong>Sie wollen mehr zum Thema CrowdRE erfahren?<\/strong><\/p>\n<p>Lesen Sie hierzu gerne auch unseren folgenden Blog-Beitrag:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/interview-crowdre-mit-der-crowd-marktpotenziale-von-softwareprodukten-heben\/\">Interview: CrowdRe \u2013 Mit der Crowd Marktpotenziale von Softwareprodukten heben<\/a><\/li>\n<\/ul>\n<\/div>\n<h3><strong>Analyse der R\u00fcckruf-Tweets des BVL (Betrachtungszeitraum: 2020\/2021)<\/strong><\/h3>\n<p>Insgesamt hat das BVL in den Jahren 2020\/2021 547 relevante R\u00fcckruf-Tweets ver\u00f6ffentlicht: 266 im Jahr 2020 und 281 im Jahr 2021. Das entspricht ungef\u00e4hr einem R\u00fcckruf-Tweet je Werktag. Dabei kann ein betroffenes Produkt mehr als einen Inverkehrbringer haben, was sich als Multiplikator auswirkt. Somit k\u00f6nnte also ohne entsprechende Warnungen der Hersteller an die Inverkehrbringer und das BVL schnell eine potenziell hohe Zahl von Konsument*innen in Mitleidenschaft gezogen werden.<\/p>\n<p>Zur Klassifizierung der verf\u00fcgbaren R\u00fcckruf-Tweets des BVL (Betrachtungszeitraum:2020\/2021) wurden diese mittels CrowdRE folgenden Gruppen zugeordnet:<\/p>\n<ul>\n<li><strong>Allergene:<\/strong> Allergene im Produkt gefunden bzw. Grenzwerte von Allergenen \u00fcberschritten<\/li>\n<li><strong>Bakterien:<\/strong> Bakterienbelastung im Produkt entdeckt bzw. Grenzwert \u00fcberschritten, beispielsweise Salmonellen, Listerien, Coli oder andere mikrobiologische Belastungen<\/li>\n<li><strong>Chemische Substanz:<\/strong> \u00dcberschreitung eines Grenzwerts einer chemischen Substanz, wie z.B. Ethylenoxid aus dem Bereich Pflanzenschutz oder Chrom\/Nickel im Bereich von Spielwaren oder Produkten mit K\u00f6rperkontakt wie Kleidung oder Schuhen<\/li>\n<li><strong>Fremdk\u00f6rper im Produkt:<\/strong> Fremdk\u00f6rper wie z.B. Plastikteile, Metallst\u00fccke oder Glasscherben im Produkt gefunden<\/li>\n<li><strong>Kennzeichnung:<\/strong> Bestimmte Inhaltsstoffe in der Kennzeichnung ausgelassen oder Mindesthaltbarkeitsdatum (MHD) falsch ausgewiesen<\/li>\n<li><strong>K\u00fchlkette:<\/strong> K\u00fchlkette nachweislich unterbrochen<\/li>\n<li><strong>Mechanische Gefahr:<\/strong> Gefahr des Aufbl\u00e4hens und Platzen oder Zerberstens der Verpackung durch chemische oder biologische Prozesse in einem luftdicht verpackten Produkt (z.B. in Glas, Becher, Konserve)<\/li>\n<li><strong>Schimmel:<\/strong> Vorhandensein von Schimmel im oder am Produkt<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-9088 gallery-columns-1 gallery-size-full'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Rueckruf-Tweetes_BVL_Lebensmittelsicherheit.png'><img loading=\"lazy\" decoding=\"async\" width=\"1211\" height=\"659\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Rueckruf-Tweetes_BVL_Lebensmittelsicherheit.png\" class=\"attachment-full size-full\" alt=\"Lebensmittelsicherheit: Auswertung (R\u00fcckruf-Tweets des BVL)\" aria-describedby=\"gallery-1-9089\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Rueckruf-Tweetes_BVL_Lebensmittelsicherheit.png 1211w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Rueckruf-Tweetes_BVL_Lebensmittelsicherheit-400x218.png 400w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Rueckruf-Tweetes_BVL_Lebensmittelsicherheit-698x380.png 698w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Rueckruf-Tweetes_BVL_Lebensmittelsicherheit-768x418.png 768w\" sizes=\"auto, (max-width: 1211px) 100vw, 1211px\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-9089'>\n\t\t\t\tAbbildung 1: Anzahl der R\u00fcckrufe in den oben beschriebenen Kategorien.\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<h3><strong>Die K\u00fchlkette in der Logistik funktioniert \u2013 Verbesserungspotenzial liegt bei der Lebensmittelproduktion<\/strong><\/h3>\n<p>Schaut man sich die Kategorien der R\u00fcckruf-Tweets genauer an, so f\u00e4llt auf, dass es in der Kategorie \u00bbK\u00fchlkette\u00ab lediglich einen Tweet und damit einen R\u00fcckruf innerhalb der beiden betrachteten Jahre gab. Somit ist ersichtlich, dass K\u00fchlketten bzw. deren ausreichende \u00dcberwachung gut funktionieren, was sich in dem einen R\u00fcckruf niederschl\u00e4gt.<\/p>\n<p>Wendet man sich jedoch anderen Kategorien zu, so wird schnell deutlich, dass 432 Tweets (ca. 80 % aller Tweets in beiden Jahren) den Kategorien \u00bbBakterien\u00ab, \u00bbFremdk\u00f6rper im Produkt\u00ab und \u00bbchemische Substanzen\u00ab zugeordnet wurden. Diese Kategorien betreffen potenziell ausnahmslos alle Konsument*innen und Nutzer*innen der betreffenden Produkte. Sie bedeuten zum Teil hohe Gesundheitsrisiken, wenn Gefahren in den Lebensmitteln unentdeckt bleiben. In vielen F\u00e4llen erfolgen die R\u00fcckrufe sehr fr\u00fchzeitig und damit rechtzeitig, sodass Schaden verhindert oder geringgehalten werden kann. Dennoch steht jeder R\u00fcckruf auch in Zusammenhang mit einem Imageschaden f\u00fcr den Hersteller des betroffenen Produkts.<\/p>\n<p>Die Kategorien \u00bbBakterien\u00ab und \u00bbFremdk\u00f6rper im Produkt\u00ab lassen in den meisten F\u00e4llen einen R\u00fcckschluss auf die Fortschrittlichkeit der Produktionstechnik oder menschliches Versagen bei Kontrolle und Hygiene zu. Menschliches Versagen wiederum k\u00f6nnte jedoch durch Innovationen in der Produktionstechnik als Faktor stark reduziert werden. Es herrschen beispielsweise oft schwierige Bedingungen zur Reinigung von Fleischkuttern, oder es fehlt die n\u00f6tige Sensorik, um Fremdk\u00f6rper in Echtzeit sicher zu erkennen und aus der Produktion zu entfernen bzw. diese anzuhalten, bis die Fremdk\u00f6rper entfernt sind.<\/p>\n<p>In der Kategorie \u00bbChemische Substanzen\u00ab liegen die Ursachen f\u00fcr deren Anwesenheit (\u00dcberschreitung von zul\u00e4ssigen Grenzwerten) h\u00e4ufig in der Produktionsstufe vor der industriellen Verarbeitung, somit in Land- und Viehwirtschaft. Hier w\u00e4re beispielsweise eine bessere Unterst\u00fctzung bei der Behandlung von Pflanzen (Crop Protection) durch entsprechende digitale Entscheidungsunterst\u00fctzungen, die z. B. angeben k\u00f6nnen, wann wie viel und welche Pflanzenschutzmittel ausgebracht werden sollen, bereits hilfreich bei der Reduzierung solcher F\u00e4lle. <a href=\"https:\/\/www.iese.fraunhofer.de\/de\/innovation_trends\/SmartFarming.html\">Smart Farming<\/a> bietet dazu eine gro\u00dfe Zahl von Optimierungs- und Dokumentationsm\u00f6glichkeiten, um eine Grenzwert\u00fcberschreitung beispielsweise bereits beim Anbau zu vermeiden oder fr\u00fch zu erkennen.<\/p>\n<h3><strong>Handlungshinweise und Verbesserungspotenziale<\/strong><\/h3>\n<p>In der bestehenden Situation zu Lebensmittelsicherheit liegen erkennbar hohe Potenziale zur Verbesserung der Produktion von Lebensmitteln.<\/p>\n<p>Verbesserungen helfen allen Seiten:<\/p>\n<ul>\n<li>Konsument*innen sind weniger gef\u00e4hrdet,<\/li>\n<li>Produzenten haben geringere Kosten durch weniger verlorene Chargen,<\/li>\n<li>Produzenten haben geringere Imagesch\u00e4den durch R\u00fcckrufe und<\/li>\n<li>Produzenten vermeiden gleichzeitig auch etwaige Regressanspr\u00fcche im Fall von gesundheitlichen Sch\u00e4den bei Konsument*innen.<\/li>\n<\/ul>\n<p>Maschinenbau, Verfahrenstechnik und moderne Produktionssteuerung mit geeigneter Sensorik und Industrie 4.0 unterst\u00fctzen die Entwicklung und den Betrieb von sicheren Maschinen f\u00fcr die Lebensmittelproduktion. Bei Bedarf kann K\u00fcnstliche Intelligenz an sinnvollen Stellen die Sicherheit durch verbesserte Erkennung von Gefahren weiter verbessern. So kann die Produktion flexibler gestaltet und somit schneller und einfacher den Anforderungen an Hygiene und Lebensmittelsicherheit in der Produktion gerecht werden. Dies kann beispielsweise durch Verbesserungen der Hardware zur einfacheren Reinigung oder sensorgest\u00fctzte und KI-basierte Vorhersage von Reinigungsintervallen erreicht werden. Ebenso l\u00e4sst sich durch smarte Sensorik (optisch, akustisch oder digital) das Eindringen von Fremdk\u00f6rpern in die Produktionsabl\u00e4ufe von Lebensmitteln erschweren oder gar ganz vermeiden.<\/p>\n<h3><strong>Die Fraunhofer-Allianz Ern\u00e4hrungswirtschaft macht Lebensmittel sicherer \u2013 jeden Tag ein St\u00fcckchen mehr.<\/strong><\/h3>\n<p>Bei der Gesamtbetrachtung des Themas \u00bbLebensmittelsicherheit\u00ab wird deutlich, dass sich etwaige L\u00f6sungsans\u00e4tze aufgrund des gewaltigen inhaltlichen Umfangs des Themas viel leichter interdisziplin\u00e4r umsetzen lassen. Darum vereint die<a href=\"https:\/\/www.fcm.fraunhofer.de\"> Fraunhofer-Allianz Ern\u00e4hrungswirtschaft<\/a> die dabei gewonnenen Erkenntnisse von mehr als einem Dutzend Fraunhofer-Instituten unter ihrem Dach. Sie forschen und entwickeln gemeinsam auch an Optimierungspotenzialen im Bereich der Lebensmittelsicherheit und arbeiten in Transferprojekten mit Unternehmen aus der Lebensmittelproduktion zusammen.<\/p>\n<p>Die M\u00f6glichkeiten, um Lebensmittelsicherheit entlang der gesamten Produktionskette nachhaltig zu verbessern, sind durch den Einsatz moderner Technologien nahezu unbegrenzt.<\/p>\n<p>Hinzu kommen M\u00f6glichkeiten zum Einsatz von <a href=\"https:\/\/www.iese.fraunhofer.de\/de\/innovation_trends\/SmartFarming.html\">Smart-Farming-Technologien<\/a>, um z. B. bereits w\u00e4hrend des Pflanzenanbaus die \u00dcberschreitung von Grenzwerten chemischer Substanzen zu vermeiden. Um dabei geltende Grenzwerte abzusichern, sind schnelle labortechnische Analysen des Wareneingangs bei Produzenten ein weiterer Aspekt zur Sicherstellung von Lebensmittelsicherheit. Damit sind sie letztlich Gesundheits-, Kosten- und Imageschutz zugleich.<\/p>\n<div class=\"info-box\">\n<p><strong>Sie wollen mehr zu den aktuellen Herausforderungen zur Verbesserung von Produktionstechnik f\u00fcr Lebensmittel erfahren und\/oder W\u00fcnsche zur Erh\u00f6hung der Lebensmittelsicherheit \u00e4u\u00dfern?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Sprechen Sie uns an! Unsere interdisziplin\u00e4r agierenden wissenschaftlichen Teams beraten und unterst\u00fctzen Sie gerne \u2013 von der Planung bis zur Umsetzung. <a href=\"https:\/\/www.iese.fraunhofer.de\/de\/ueberuns\/partner_netzwerke\/fcm.html\">Mehr Infos dazu finden Sie hier.<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Lebensmittelsicherheit geht uns alle an! \u2013 Klingt wie ein Werbeslogan, ist es aber nicht. Mehr denn je wird heute auf die Sicherheit unserer Nahrung geachtet. Und das ist auch gut so! Aber was passiert, wenn Lebensmittel einmal nicht sicher sind&#8230;<\/p>\n","protected":false},"author":19,"featured_media":9107,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[211,423,210],"tags":[209,197,142,48,131,127],"coauthors":[58],"class_list":["post-9088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digitale-transformation","category-nachhaltigkeit","category-smart-farming","tag-cognitive-agriculture","tag-crowdre","tag-digitale-oekosysteme","tag-digitalisierung","tag-plattformoekonomie","tag-requirements-engineering"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf - Blog des Fraunhofer IESE<\/title>\n<meta name=\"description\" content=\"Lebensmittelsicherheit geht alle an! \u2013 Wir erkl\u00e4ren, wie CrowdRE Lebensmittelr\u00fcckrufe klassifizieren und Optimierungspotenziale erkennen kann.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf - Blog des Fraunhofer IESE\" \/>\n<meta property=\"og:description\" content=\"Lebensmittelsicherheit geht alle an! \u2013 Wir erkl\u00e4ren, wie CrowdRE Lebensmittelr\u00fcckrufe klassifizieren und Optimierungspotenziale erkennen kann.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/\" \/>\n<meta property=\"og:site_name\" content=\"Fraunhofer IESE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FraunhoferIESE\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-10T09:08:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T09:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Lebensmittelsicherheit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1496\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FraunhoferIESE\" \/>\n<meta name=\"twitter:site\" content=\"@FraunhoferIESE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/\"},\"author\":{\"name\":\"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/person\\\/9f336c9aed5cbbfa1d97fb74474ef6cd\"},\"headline\":\"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf\",\"datePublished\":\"2022-03-10T09:08:56+00:00\",\"dateModified\":\"2025-08-19T09:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/\"},\"wordCount\":1530,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Lebensmittelsicherheit.jpg\",\"keywords\":[\"Cognitive Agriculture\",\"CrowdRE\",\"Digitale \u00d6kosysteme\",\"Digitalisierung\",\"Plattform\u00f6konomie\",\"Requirements Engineering\"],\"articleSection\":[\"Digitale Transformation\",\"Nachhaltigkeit\",\"Smart Farming\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/\",\"name\":\"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf - Blog des Fraunhofer IESE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Lebensmittelsicherheit.jpg\",\"datePublished\":\"2022-03-10T09:08:56+00:00\",\"dateModified\":\"2025-08-19T09:42:55+00:00\",\"description\":\"Lebensmittelsicherheit geht alle an! \u2013 Wir erkl\u00e4ren, wie CrowdRE Lebensmittelr\u00fcckrufe klassifizieren und Optimierungspotenziale erkennen kann.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Lebensmittelsicherheit.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Lebensmittelsicherheit.jpg\",\"width\":1496,\"height\":750,\"caption\":\"Lebensmittelsicherheit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/lebensmittelsicherheit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\",\"name\":\"Fraunhofer IESE\",\"description\":\"Blog des Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\",\"name\":\"Fraunhofer IESE\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/fhg_iese_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/fhg_iese_logo.png\",\"width\":183,\"height\":50,\"caption\":\"Fraunhofer IESE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FraunhoferIESE\\\/\",\"https:\\\/\\\/x.com\\\/FraunhoferIESE\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fraunhoferiese\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/FraunhoferIESE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/person\\\/9f336c9aed5cbbfa1d97fb74474ef6cd\",\"name\":\"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/1464168343523_doerr-joerg-95x120-96x96.jpgafd88879903348c74612d69564a467a6\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/1464168343523_doerr-joerg-95x120-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/1464168343523_doerr-joerg-95x120-96x96.jpg\",\"caption\":\"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr\"},\"description\":\"J\u00f6rg D\u00f6rr ist wissenschaftlicher Institutsleiter des Fraunhofer IESE und Inhaber des Lehrstuhls \u00bbDigital Farming\u00ab an der TU Kaiserslautern. Bereits seit 2020 ist er Mitglied der erweiterten Institutsleitung des Fraunhofer IESE in Kaiserslautern. Darin verantwortet er die Forschungsprogramme des Instituts und leitet seit 2020 das Programm \u00bbSmart Farming\u00ab am Institut. Sein Arbeitsschwerpunkt an der TU sowie am Fraunhofer IESE umfasst Software und Systems Engineering, insbesondere f\u00fcr Anwendungen im Digital Farming. J\u00f6rg D\u00f6rr war von 2018 bis 2020 Co-Head Business Development. Von 2010-2019 war er Leiter der Hauptabteilung \u00bbInformation Systems\u00ab und von 2005-2010 Leiter der Abteilung \u00bbRequirements und Usability Engineering\u00ab. Er promovierte im Jahre 2010 zu nicht-funktionalen Aspekten in der Anforderungsspezifikation. Er studierte an der Universit\u00e4t Kaiserslautern Informatik mit Nebenfach Elektrotechnik. Seit 2002 arbeitet er am Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering IESE. J\u00f6rg D\u00f6rr verf\u00fcgt \u00fcber umfassende Kenntnisse auf dem Gebiet des Software und Systems Engineerings, des Requirements Engineerings sowie der Datennutzungskontrolle. Er ist in diversen Branchen aktiv, mit Fokus im Bereich Smart Farming. Er ist Autor von mehr als 150 akademischen und industrienahen Publikationen. Seit 2006 ist er als Dozent u.a. zum Thema Requirements Engineering und Agile Methoden, seit 2021 auch zu Digital Farming an Universit\u00e4ten aktiv. J\u00f6rg D\u00f6rr engagiert sich in der GI (Gesellschaft f\u00fcr Informatik e.V.), war mehrere Jahre lang Sprecher der Fachgruppe Requirements Engineering und ist Gr\u00fcndungsmitglied der GI Regionalgruppe Kaiserslautern. Weiterhin ist er fachlicher Leiter der User Group Requirements Engineering der Softwareforen und in diversen nationalen und internationalen Programmaussch\u00fcssen aktiv. --- J\u00f6rg D\u00f6rr is Scientific Director of the Fraunhofer IESE and holds the \u201cDigital Farming\u201d chair at TU Kaiserslautern. Furthermore, he has been a member of the extended institute management of Fraunhofer IESE in Kaiserslautern since 2020. In this position, he is responsible for the institute\u2019s research programs and has been leading the research program \u201cSmart Farming\u201d at the institute since 2020. His work at TUK as well as at Fraunhofer IESE focuses on software and systems engineering, especially for Digital Farming applications. J\u00f6rg D\u00f6rr was Co-Head Business Development from 2018 to 2020. From 2010-2019, he was manager of the \u201cInformation Systems\u201d division and from 2005-2010 head of the \u201cRequirements and Usability Engineering\u201d department. He received his PhD in 2010 with a dissertation on non-functional aspects in requirements specifications. He studied Computer Science with a minor in Electrical Engineering at the University of Kaiserslautern, Germany. Since 2002, he has been working at the Fraunhofer Institute for Experimental Software Engineering IESE. J\u00f6rg D\u00f6rr has extensive knowledge in the field of software and systems engineering, requirements engineering, as well as data usage control. He is active in diverse industries, with a focus on Smart Farming. He is the author of more than 150 academic and industry-oriented publications. Since 2006, he has been active as a university lecturer on topics such as Requirements Engineering and Agile Methods, and since 2021 also on Digital Farming. J\u00f6rg D\u00f6rr is actively involved in the GI (Gesellschaft f\u00fcr Informatik e.V., German Informatics Society), was spokesperson of the expert group \u201cRequirements Engineering\u201d for several years, and is a founding member of the GI Regional Group Kaiserslautern. Furthermore, he is the expert head of the User Group Requirements Engineering of Softwareforen and active in various national and international program committees.\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/author\\\/joerg-doerr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf - Blog des Fraunhofer IESE","description":"Lebensmittelsicherheit geht alle an! \u2013 Wir erkl\u00e4ren, wie CrowdRE Lebensmittelr\u00fcckrufe klassifizieren und Optimierungspotenziale erkennen kann.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/","og_locale":"de_DE","og_type":"article","og_title":"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf - Blog des Fraunhofer IESE","og_description":"Lebensmittelsicherheit geht alle an! \u2013 Wir erkl\u00e4ren, wie CrowdRE Lebensmittelr\u00fcckrufe klassifizieren und Optimierungspotenziale erkennen kann.","og_url":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/","og_site_name":"Fraunhofer IESE","article_publisher":"https:\/\/www.facebook.com\/FraunhoferIESE\/","article_published_time":"2022-03-10T09:08:56+00:00","article_modified_time":"2025-08-19T09:42:55+00:00","og_image":[{"width":1496,"height":750,"url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Lebensmittelsicherheit.jpg","type":"image\/jpeg"}],"author":"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr","twitter_card":"summary_large_image","twitter_creator":"@FraunhoferIESE","twitter_site":"@FraunhoferIESE","twitter_misc":{"Verfasst von":"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten","Written by":"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/#article","isPartOf":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/"},"author":{"name":"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/person\/9f336c9aed5cbbfa1d97fb74474ef6cd"},"headline":"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf","datePublished":"2022-03-10T09:08:56+00:00","dateModified":"2025-08-19T09:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/"},"wordCount":1530,"publisher":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Lebensmittelsicherheit.jpg","keywords":["Cognitive Agriculture","CrowdRE","Digitale \u00d6kosysteme","Digitalisierung","Plattform\u00f6konomie","Requirements Engineering"],"articleSection":["Digitale Transformation","Nachhaltigkeit","Smart Farming"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/","url":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/","name":"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf - Blog des Fraunhofer IESE","isPartOf":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Lebensmittelsicherheit.jpg","datePublished":"2022-03-10T09:08:56+00:00","dateModified":"2025-08-19T09:42:55+00:00","description":"Lebensmittelsicherheit geht alle an! \u2013 Wir erkl\u00e4ren, wie CrowdRE Lebensmittelr\u00fcckrufe klassifizieren und Optimierungspotenziale erkennen kann.","breadcrumb":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/#primaryimage","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Lebensmittelsicherheit.jpg","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Lebensmittelsicherheit.jpg","width":1496,"height":750,"caption":"Lebensmittelsicherheit"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/lebensmittelsicherheit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.iese.fraunhofer.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Lebensmittelsicherheit in Deutschland: Viel Platz f\u00fcr Innovation zwischen Produktion und R\u00fcckruf"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#website","url":"https:\/\/www.iese.fraunhofer.de\/blog\/","name":"Fraunhofer IESE","description":"Blog des Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering","publisher":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.fraunhofer.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization","name":"Fraunhofer IESE","url":"https:\/\/www.iese.fraunhofer.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/fhg_iese_logo.png","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/fhg_iese_logo.png","width":183,"height":50,"caption":"Fraunhofer IESE"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FraunhoferIESE\/","https:\/\/x.com\/FraunhoferIESE","https:\/\/www.linkedin.com\/company\/fraunhoferiese\/","https:\/\/www.youtube.com\/c\/FraunhoferIESE"]},{"@type":"Person","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/person\/9f336c9aed5cbbfa1d97fb74474ef6cd","name":"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/1464168343523_doerr-joerg-95x120-96x96.jpgafd88879903348c74612d69564a467a6","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/1464168343523_doerr-joerg-95x120-96x96.jpg","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/1464168343523_doerr-joerg-95x120-96x96.jpg","caption":"Prof. Dr.-Ing. J\u00f6rg D\u00f6rr"},"description":"J\u00f6rg D\u00f6rr ist wissenschaftlicher Institutsleiter des Fraunhofer IESE und Inhaber des Lehrstuhls \u00bbDigital Farming\u00ab an der TU Kaiserslautern. Bereits seit 2020 ist er Mitglied der erweiterten Institutsleitung des Fraunhofer IESE in Kaiserslautern. Darin verantwortet er die Forschungsprogramme des Instituts und leitet seit 2020 das Programm \u00bbSmart Farming\u00ab am Institut. Sein Arbeitsschwerpunkt an der TU sowie am Fraunhofer IESE umfasst Software und Systems Engineering, insbesondere f\u00fcr Anwendungen im Digital Farming. J\u00f6rg D\u00f6rr war von 2018 bis 2020 Co-Head Business Development. Von 2010-2019 war er Leiter der Hauptabteilung \u00bbInformation Systems\u00ab und von 2005-2010 Leiter der Abteilung \u00bbRequirements und Usability Engineering\u00ab. Er promovierte im Jahre 2010 zu nicht-funktionalen Aspekten in der Anforderungsspezifikation. Er studierte an der Universit\u00e4t Kaiserslautern Informatik mit Nebenfach Elektrotechnik. Seit 2002 arbeitet er am Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering IESE. J\u00f6rg D\u00f6rr verf\u00fcgt \u00fcber umfassende Kenntnisse auf dem Gebiet des Software und Systems Engineerings, des Requirements Engineerings sowie der Datennutzungskontrolle. Er ist in diversen Branchen aktiv, mit Fokus im Bereich Smart Farming. Er ist Autor von mehr als 150 akademischen und industrienahen Publikationen. Seit 2006 ist er als Dozent u.a. zum Thema Requirements Engineering und Agile Methoden, seit 2021 auch zu Digital Farming an Universit\u00e4ten aktiv. J\u00f6rg D\u00f6rr engagiert sich in der GI (Gesellschaft f\u00fcr Informatik e.V.), war mehrere Jahre lang Sprecher der Fachgruppe Requirements Engineering und ist Gr\u00fcndungsmitglied der GI Regionalgruppe Kaiserslautern. Weiterhin ist er fachlicher Leiter der User Group Requirements Engineering der Softwareforen und in diversen nationalen und internationalen Programmaussch\u00fcssen aktiv. --- J\u00f6rg D\u00f6rr is Scientific Director of the Fraunhofer IESE and holds the \u201cDigital Farming\u201d chair at TU Kaiserslautern. Furthermore, he has been a member of the extended institute management of Fraunhofer IESE in Kaiserslautern since 2020. In this position, he is responsible for the institute\u2019s research programs and has been leading the research program \u201cSmart Farming\u201d at the institute since 2020. His work at TUK as well as at Fraunhofer IESE focuses on software and systems engineering, especially for Digital Farming applications. J\u00f6rg D\u00f6rr was Co-Head Business Development from 2018 to 2020. From 2010-2019, he was manager of the \u201cInformation Systems\u201d division and from 2005-2010 head of the \u201cRequirements and Usability Engineering\u201d department. He received his PhD in 2010 with a dissertation on non-functional aspects in requirements specifications. He studied Computer Science with a minor in Electrical Engineering at the University of Kaiserslautern, Germany. Since 2002, he has been working at the Fraunhofer Institute for Experimental Software Engineering IESE. J\u00f6rg D\u00f6rr has extensive knowledge in the field of software and systems engineering, requirements engineering, as well as data usage control. He is active in diverse industries, with a focus on Smart Farming. He is the author of more than 150 academic and industry-oriented publications. Since 2006, he has been active as a university lecturer on topics such as Requirements Engineering and Agile Methods, and since 2021 also on Digital Farming. J\u00f6rg D\u00f6rr is actively involved in the GI (Gesellschaft f\u00fcr Informatik e.V., German Informatics Society), was spokesperson of the expert group \u201cRequirements Engineering\u201d for several years, and is a founding member of the GI Regional Group Kaiserslautern. Furthermore, he is the expert head of the User Group Requirements Engineering of Softwareforen and active in various national and international program committees.","url":"https:\/\/www.iese.fraunhofer.de\/blog\/author\/joerg-doerr\/"}]}},"jetpack_featured_media_url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2022\/03\/Lebensmittelsicherheit.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/9088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/comments?post=9088"}],"version-history":[{"count":6,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/9088\/revisions"}],"predecessor-version":[{"id":14082,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/9088\/revisions\/14082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/media\/9107"}],"wp:attachment":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/media?parent=9088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/categories?post=9088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/tags?post=9088"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/coauthors?post=9088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}