{"id":8561,"date":"2021-10-21T09:53:59","date_gmt":"2021-10-21T07:53:59","guid":{"rendered":"https:\/\/www.iese.fraunhofer.de\/blog\/?p=8561"},"modified":"2024-02-19T11:23:04","modified_gmt":"2024-02-19T10:23:04","slug":"fachsymposium-smartes-quartier","status":"publish","type":"post","link":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/","title":{"rendered":"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft"},"content":{"rendered":"<p class=\"lead\">In diesem Blog-Beitrag blicken wir zur\u00fcck auf das <a href=\"https:\/\/pfaff-reallabor.de\/fachsymposium\/\">Fachsymposium<\/a> zu unserem <a href=\"https:\/\/www.iese.fraunhofer.de\/de\/customers_industries\/referenzprojekt-enstadt-pfaff.html\">Projekt \u00bbEnStadt:Pfaff\u00ab<\/a>, in welchem wir L\u00f6sungen f\u00fcr ein nachhaltiges, klimafreundliches und smartes Quartier der Zukunft entwickeln. Ziel des Fachsymposiums, welches im September 2021 in der Fruchthalle Kaiserslautern statttfand, war es, die bisher im <a href=\"https:\/\/pfaff-reallabor.de\/\">Projekt \u00bbEnStadt:Pfaff\u00ab<\/a> erreichten Fortschritte und Ergebnisse einer breiten \u00d6ffentlichkeit zu pr\u00e4sentieren sowie den Teilnehmenden Einblicke zu m\u00f6glichen L\u00f6sungen f\u00fcr die nachhaltige Gestaltung der Mobilit\u00e4t und Energieversorgung in einem Modell-Quartier \u2013 dem in Kaiserslautern angesiedelten, ehemaligen Pfaff-Gel\u00e4nde \u2013 n\u00e4herzubringen. Au\u00dferdem informierten wir bei dem Event \u00fcber digitale Services f\u00fcr B\u00fcrger*innen, die zu einer hohen Lebensqualit\u00e4t des smarten Quartiers beitragen sollen. Nun aber erst nochmal ganz zur\u00fcck zum Anfang!<\/p>\n<p>Am 30. September fanden wir, das <a href=\"https:\/\/www.iese.fraunhofer.de\/\">Fraunhofer IESE<\/a>, und die weiteren am Projekt \u00bbEnStadt:Pfaff\u00ab beteiligten Konsortialpartner zusammen und stellten unsere bisherigen Projektergebnisse zur neuen, nachhaltigen Gestaltung des ehemaligen Pfaff-Quartiers in Kaiserslautern im Rahmen einer hybriden Veranstaltung, die in der Fruchthalle in Kaiserslautern stattfand und parallel dazu online \u00fcbertragen wurde, vor. Das Programm des Fachsymposiums bot dabei eine Mischung aus Fokusbeitr\u00e4gen, Pitches, einer Podiumsdiskussion sowie einleitenden Worten aus der Politik und vom F\u00f6rdergeber. Der rege Austausch mit den virtuell und real anwesenden B\u00fcrger*innen und Forscher*innen reicherte die Veranstaltung durch spannende Nachfragen an, sodass das Symposium als interessanter Dialog zwischen Forschung, Politik und \u00d6ffentlichkeit diente.<\/p>\n<div class=\"info-box\">\n<p>Infobox: Die Pr\u00e4sentationen und das Gesamtvideo k\u00f6nnen <a href=\"https:\/\/pfaff-reallabor.de\/fachsymposium\/\">online abgerufen<\/a> werden.<\/p>\n<\/div>\n<p>Wir boten den Anwesenden dabei im Zuge eines ca. f\u00fcnfmin\u00fctigen Pitches einen \u00dcberblick zum Thema \u00bbDigitalisierung eines klimaneutralen Stadtquartiers\u00ab. Dazu gingen wir u. a. darauf ein, wie sich reale Welten \u2013 in diesem Fall unser Pfaff-Quartier \u2013 durch den Einsatz eines digitalen und smarten Quartiers\u00f6kosystems erg\u00e4nzen lassen. Es gibt in dem von uns vorgesehenen \u00d6kosystem eine Plattform mit darauf laufenden Diensten, die die Nutzenden dabei unterst\u00fctzen sollen, sich klimafreundlich zu verhalten. Wir m\u00f6chten den Blick stets auf den B\u00fcrger und die B\u00fcrgerin richten, sprich: Es geht nicht darum, (Software-)Technik um der Technik willen zu etablieren, sondern die Bed\u00fcrfnisse der Nutzenden zu adressieren.<\/p>\n<figure id=\"attachment_8567\" aria-describedby=\"caption-attachment-8567\" style=\"width: 698px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8567 size-large\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-1-698x393.png\" alt=\"Das Pfaffquartier als smartes Quartier mit digitalem Quartiers\u00f6kosystem\" width=\"698\" height=\"393\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-1-698x393.png 698w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-1-400x225.png 400w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-1-768x432.png 768w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-1.png 1280w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-8567\" class=\"wp-caption-text\">Abbildung 1: Pfaff-Quartier mit digitalem Quartiers\u00f6kosystem<\/figcaption><\/figure>\n<p>Anhand zweier, konkreter Beispiele k\u00f6nnen und konnten wir auch beim Fachsymposium aufzeigen, wie eine solche Unterst\u00fctzung aussehen kann: <a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/minilautern\/\">\u00bbMiniLautern\u00ab<\/a> und <a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/klimaneutralitaet-pfaff-quartier-2029\/\">\u00bbFish n&#8216;\u00a0Tipps\u00ab<\/a>.<\/p>\n<p><a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/minilautern\/\">\u00bbMiniLautern\u00ab<\/a> ist ein Spiel, welches wir entwickelt haben und mit dem wir \u00fcber neue Mobilit\u00e4tskonzepte und -ma\u00dfnahmen informieren wollen. Denn diese sind \u2013 obwohl vorhanden \u2013 vielen B\u00fcrger*innen meist (noch) unbekannt. Im Spiel \u00bbMiniLautern\u00ab haben die Spielenden daher die Aufgabe, die Ma\u00dfnahmen auszuw\u00e4hlen, die den besten Effekt auf Umweltschutz, Lebensqualit\u00e4t und individuelle Zufriedenheit haben. Ein Spieler bzw. eine Spielerin w\u00e4hlt dazu pro Runde eine Ma\u00dfnahme aus und erh\u00e4lt anschlie\u00dfend Feedback zu den genannten Aspekten. Damit zeigen wir auf, dass es sowohl ein F\u00fcr als auch ein Wider mit Blick auf neue Mobilit\u00e4tsma\u00dfnahmen gibt. Weniger Autos im Pfaff-Quartier sind unter anderem gut f\u00fcr die Umwelt; wenn ein Bewohner allerdings die schweren Eink\u00e4ufe nicht mehr vor seine Haust\u00fcre fahren kann, mag es durchaus auch kritische Stimmen geben. F\u00fcr solche Situationen m\u00f6chten wir ein Bewusstsein schaffen, Bedenken ernst nehmen und die Spielenden bei unseren \u00dcberlegungen und der Entwicklung neuer L\u00f6sungen mitnehmen. So lernen sie einfach die Ma\u00dfnahmen und deren Auswirkungen kennen.<\/p>\n<p>Zusammengefasst m\u00f6chten wir mit \u00bbMiniLautern\u00ab also dazu einladen, das Thema \u00bbNachhaltige Mobilit\u00e4t\u00ab spielerisch zu erkunden und idealerweise die ein oder anderen Mobilit\u00e4tsma\u00dfnahmen auch selbst auszuprobieren, um so einen Beitrag zu klimafreundlichem Verhalten zu leisten. <a href=\"https:\/\/www.minilautern.de\/\">Spielen Sie doch gerne auch einmal eine Runde!<\/a><\/p>\n<figure id=\"attachment_8569\" aria-describedby=\"caption-attachment-8569\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8569 size-large\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-2-698x393.png\" alt=\"MiniLautern Spiel: Auswahl von Mobilit\u00e4tskonzepten zur Demonstration des Lebens in einem smarten Quartier\" width=\"698\" height=\"393\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-2-698x393.png 698w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-2-400x225.png 400w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-2-768x432.png 768w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-2.png 1280w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-8569\" class=\"wp-caption-text\">Abbildung 2: \u00bbMiniLautern\u00ab-Spiel: Auswahl von Mobilit\u00e4tskonzepten<\/figcaption><\/figure>\n<figure id=\"attachment_8570\" aria-describedby=\"caption-attachment-8570\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8570 size-large\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-3-698x393.png\" alt=\"MiniLautern Spiel: Reaktion auf ausgew\u00e4hlte Mobilit\u00e4tsma\u00dfnahme\" width=\"698\" height=\"393\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-3-698x393.png 698w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-3-400x225.png 400w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-3-768x432.png 768w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-3.png 1280w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-8570\" class=\"wp-caption-text\">Abbildung 3: \u00bbMiniLautern\u00ab-Spiel: Reaktion auf ausgew\u00e4hlte Mobilit\u00e4tsma\u00dfnahme<\/figcaption><\/figure>\n<p>Das zweite Beispiel ist die <a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/klimaneutralitaet-pfaff-quartier-2029\/\">\u00bbFish n&#8216;\u00a0Tipps\u00ab<\/a>-App. Mit dieser App, die im Bereich Energie und der passenden Community angesiedelt ist, geben wir den Nutzer*innen einen digitalen Assistenten an die Hand, der Hinweise beim Energiesparen gibt und das Vernetzen von Personen im smarten Quartier erm\u00f6glicht.<\/p>\n<p>Die Kernidee dabei ist, dass die App-Nutzer*innen einen pers\u00f6nlichen Avatar in Form eines Fisches bekommen, welcher ihnen konkrete Hinweise und Tipps gibt und erkl\u00e4rt, wie man sich klimafreundlicher Verhalten kann. Die Tipps kommen dazu aus zwei verschiedenen Quellen:<\/p>\n<ol>\n<li>Zun\u00e4chst k\u00f6nnen sie von der Community eingestellt werden, d.h. jeder Nutzende der App kann Tipps zum klimafreundlichen Verhalten formulieren, die dann anderen helfen k\u00f6nnen, ihr eigenes Leben ein bisschen anzupassen, ohne zu starken Verzicht zu \u00fcben.<\/li>\n<li>Zudem kann das \u00d6kosystem selbst Tipps generieren. Der Gedanke dabei ist folgender: Wenn unsere App anderen Apps und Diensten im digitalen \u00d6kosystem \u00bbzuh\u00f6rt\u00ab, kann sie passende Tipps generieren. Wenn beispielsweise das Wetter gut ist (was unsere App wei\u00df, da ein Wetterdienst im \u00d6kosystem l\u00e4uft), und bei einer nahen Fahrradleihstation noch Fahrr\u00e4der ausgeliehen werden k\u00f6nnen (was unsere App ebenfalls wei\u00df, da die Leihstation digital verbunden ist) und unsere App den Terminkalender einer Nutzer*in kennt und somit wei\u00df, dass sie nur eine kurze Strecke zur\u00fccklegen muss, dann kann vom \u00bbSystem\u00ab der Tipp generiert werden, das Fahrrad anstatt des Autos f\u00fcr das Zur\u00fccklegen einer gewissen Strecke zu verwenden.<\/li>\n<\/ol>\n<p>Um ansprechend zu wirken, hat die App ein spielerisches Look and Feel und enth\u00e4lt zudem Gamification-Elemente wie ein Punktesystem f\u00fcr das Nutzen von Tipps.<\/p>\n<figure id=\"attachment_8572\" aria-describedby=\"caption-attachment-8572\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8572 size-large\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-4-698x393.png\" alt=\"Fish 'n Tipps App: Tipps aus der Community f\u00fcr ein smartes Quartiersleben\" width=\"698\" height=\"393\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-4-698x393.png 698w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-4-400x225.png 400w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-4-768x432.png 768w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-4.png 1280w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-8572\" class=\"wp-caption-text\">Abbildung 4: \u00bbFish n&#8216;\u00a0Tipps\u00ab-App: Tipps aus der Community<\/figcaption><\/figure>\n<figure id=\"attachment_8573\" aria-describedby=\"caption-attachment-8573\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8573 size-large\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-5-698x393.png\" alt=\"Fish 'n Tipps App: Tipps aus dem Quartiers\u00f6kosystem f\u00fcr ein smartes Quartiersleben\" width=\"698\" height=\"393\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-5-698x393.png 698w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-5-400x225.png 400w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-5-768x432.png 768w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-5.png 1280w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-8573\" class=\"wp-caption-text\">Abbildung 5: \u00bbFish n&#8216; Tipps\u00ab-App: Tipps aus dem Quartiers\u00f6kosystem<\/figcaption><\/figure>\n<p>Die beiden beim Fachsymposium gezeigten Beispiele sind Streiflichter, die aufzeigen, wie die Digitalisierung eines smarten Stadtquartiers klimafreundliches Verhalten unterst\u00fctzen kann.<\/p>\n<p>In den vergangenen Projektjahren ist allerdings noch viel mehr passiert! Wir entwickelten z. B. einen Plattform-Mock, um neue prototypische Dienste schneller ausprobieren zu k\u00f6nnen. Zudem erstellten wir einen Smart-Home-Simulator sowie einen Quartierssimulator und etablierten den <a href=\"https:\/\/pfaff-reallabor.de\/pfafffunk-gestartet\/\">PfaffFunk<\/a> als modernen Dienst zum Austausch und zur Verbreitung von Neuigkeiten aus dem Projekt. Ebenso k\u00f6nnen interessierte B\u00fcrger*innen dar\u00fcber in Kontakt treten. Abgesehen davon starteten wir im Rahmen unserer Quartierswerkstatt einen <a href=\"https:\/\/www.youtube.com\/channel\/UCK8LjvcvaCHBF-voo0qcqqA\">Youtube Kanal<\/a>, auf dem wir regelm\u00e4\u00dfig Videos zu neuen Inhalten einstellen.<\/p>\n<div class=\"info-box\">\n<p><strong>Jetzt mitmachen beim PFAFF HACK 2021!<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Da Wissenschaft vom steten Austausch lebt und dadurch umso st\u00e4rker befl\u00fcgelt wird, wollen wir nat\u00fcrlich so viele Menschen wie m\u00f6glich an unserer Forschung teilhaben lassen. Dazu etablierten wir 2018 zum Beispiel unseren j\u00e4hrlichen Hackathon \u2013 den <a href=\"https:\/\/pfaffhack.iese.de\/\">PFAFF HACK<\/a>. Bei dem Event wird in divers aufgestellten Teams \u00fcber mehrere Tage hinweg an neuen, nachhaltigen und klimafreundlichen L\u00f6sungen f\u00fcr die Zukunft get\u00fcftelt.<\/p>\n<p>&nbsp;<\/p>\n<p>Aktuell sind wir auch wieder auf der Suche nach kreativen K\u00f6pfen. Denn der vierte PFAFF HACK findet bereits im November 2021 statt. Noch gibt es freie Pl\u00e4tze f\u00fcr den Hackathon. <a href=\"https:\/\/pfaffhack.iese.de\/de\/\">Also gleich anmelden<\/a>.<\/p>\n<\/div>\n<p>Zudem haben wir ein <a href=\"https:\/\/oc.iese.de\/index.php\/s\/oBiC3Ilyf0eWalM\">IKT Konzept<\/a> zu den Themen verfasst und eine <a href=\"https:\/\/www.mdpi.com\/2624-6511\/4\/2\/35\">wissenschaftliche Abhandlung<\/a> (in Englisch) dazu geschrieben.<\/p>\n<p>Unser Fazit lautet: Es gibt viele Ideen, Konzepte, L\u00f6sungen und konkrete Schritte, wie die Digitalisierung bei dem Thema \u00bbklimafreundliches, smartes Stadtquartier\u00ab unterst\u00fctzen kann. Dies konnten wir in diesem Beitrag anhand einiger Beispiele skizzieren. Sie dienen nicht nur als Ideengeber, sondern sollen auch die \u00bbFurcht\u00ab vor der gro\u00dfen Herausforderung \u00bbmehr klimafreundlich zu sein\u00ab ein wenig reduzieren.<\/p>\n<p>Daher freuen wir uns, wenn viele Personen unsere bisher erarbeiteten L\u00f6sungen und Formate anwenden, mit uns in Kontakt treten und mit weiteren Ideen zur Realisierung einer digital-unterst\u00fctzten, nachhaltigeren Zukunft beitragen.<\/p>\n<p>Kontaktieren Sie uns daher gerne <a href=\"mailto: frank.elberzhager@iese.fraunhofer.de\">per Mail<\/a>.<\/p>\n<figure id=\"attachment_8574\" aria-describedby=\"caption-attachment-8574\" style=\"width: 698px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8574 size-large\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-6-698x393.png\" alt=\"Gesamtansicht, die darstellt, wie ein smartes Quartier, vernetzt durch ein digitales Quartiers\u00f6kosystem, aussehen k\u00f6nnte\" width=\"698\" height=\"393\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-6-698x393.png 698w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-6-400x225.png 400w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-6-768x432.png 768w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Fachsymposium-Bild-6.png 1280w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/><figcaption id=\"caption-attachment-8574\" class=\"wp-caption-text\">Abbildung 6: Ausschnitt von Beitr\u00e4gen f\u00fcr das digitale Quartiers\u00f6kosystem<\/figcaption><\/figure>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-8575\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Foerderlogo-400x208.jpg\" alt=\"\" width=\"400\" height=\"208\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Foerderlogo-400x208.jpg 400w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Foerderlogo-698x363.jpg 698w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Foerderlogo-768x399.jpg 768w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Foerderlogo-1320x686.jpg 1320w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Pfaff-Foerderlogo.jpg 1367w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In diesem Blog-Beitrag blicken wir zur\u00fcck auf das Fachsymposium zu unserem Projekt \u00bbEnStadt:Pfaff\u00ab, in welchem wir L\u00f6sungen f\u00fcr ein nachhaltiges, klimafreundliches und smartes Quartier der Zukunft entwickeln. Ziel des Fachsymposiums, welches im September 2021 in der Fruchthalle Kaiserslautern statttfand, war&#8230;<\/p>\n","protected":false},"author":25,"featured_media":8564,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[424,13],"tags":[142],"coauthors":[38],"class_list":["post-8561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-smart-city","category-veranstaltung","tag-digitale-oekosysteme"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft - Blog des Fraunhofer IESE<\/title>\n<meta name=\"description\" content=\"Im Projekt \u00bbEnStadt:Pfaff\u00ab entwickeln wir L\u00f6sungen f\u00fcr ein nachhaltiges und smartes (Stadt-)Quartier der Zukunft. Diese stellten wir k\u00fcrzlich beim Fachsymposium vor.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft - Blog des Fraunhofer IESE\" \/>\n<meta property=\"og:description\" content=\"Im Projekt \u00bbEnStadt:Pfaff\u00ab entwickeln wir L\u00f6sungen f\u00fcr ein nachhaltiges und smartes (Stadt-)Quartier der Zukunft. Diese stellten wir k\u00fcrzlich beim Fachsymposium vor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/\" \/>\n<meta property=\"og:site_name\" content=\"Fraunhofer IESE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FraunhoferIESE\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-21T07:53:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T10:23:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Fachsymposium-Teaserbild.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1785\" \/>\n\t<meta property=\"og:image:height\" content=\"1089\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Frank Elberzhager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FraunhoferIESE\" \/>\n<meta name=\"twitter:site\" content=\"@FraunhoferIESE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Frank Elberzhager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Dr. Frank Elberzhager\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/\"},\"author\":{\"name\":\"Dr. Frank Elberzhager\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/person\\\/6ede08c487a56db3656eb7816a65ac9a\"},\"headline\":\"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft\",\"datePublished\":\"2021-10-21T07:53:59+00:00\",\"dateModified\":\"2024-02-19T10:23:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/\"},\"wordCount\":1309,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Fachsymposium-Teaserbild.jpg\",\"keywords\":[\"Digitale \u00d6kosysteme\"],\"articleSection\":[\"Smart City\",\"Veranstaltung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/\",\"name\":\"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft - Blog des Fraunhofer IESE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Fachsymposium-Teaserbild.jpg\",\"datePublished\":\"2021-10-21T07:53:59+00:00\",\"dateModified\":\"2024-02-19T10:23:04+00:00\",\"description\":\"Im Projekt \u00bbEnStadt:Pfaff\u00ab entwickeln wir L\u00f6sungen f\u00fcr ein nachhaltiges und smartes (Stadt-)Quartier der Zukunft. Diese stellten wir k\u00fcrzlich beim Fachsymposium vor.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Fachsymposium-Teaserbild.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Fachsymposium-Teaserbild.jpg\",\"width\":1785,\"height\":1089,\"caption\":\"Pfaff Fachsymposium\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/fachsymposium-smartes-quartier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\",\"name\":\"Fraunhofer IESE\",\"description\":\"Blog des Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\",\"name\":\"Fraunhofer IESE\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/fhg_iese_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/fhg_iese_logo.png\",\"width\":183,\"height\":50,\"caption\":\"Fraunhofer IESE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FraunhoferIESE\\\/\",\"https:\\\/\\\/x.com\\\/FraunhoferIESE\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fraunhoferiese\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/FraunhoferIESE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/person\\\/6ede08c487a56db3656eb7816a65ac9a\",\"name\":\"Dr. Frank Elberzhager\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/elberzhager_frank_web-96x96.jpg572de2b19cccbdfa7b2cf475fff214a4\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/elberzhager_frank_web-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/elberzhager_frank_web-96x96.jpg\",\"caption\":\"Dr. Frank Elberzhager\"},\"description\":\"Dr. Frank Elberzhager leitet die Abteilung Archicture-Centric Engineering am Fraunhofer IESE. Seit \u00fcber f\u00fcnfzehn Jahren leitet er Forschungs- und Industrieprojekte unterschiedlicher Gr\u00f6\u00dfe und Kritikalit\u00e4t. Inhaltich besch\u00e4ftigt er sich vor allem mit Themen rund um Softwarequalit\u00e4tssicherung und \u2013architektur. Aktueller Fokus seiner Forschungsarbeiten sind \u00d6kosysteme in digitalen Stadtquartieren und l\u00e4ndlichen Regionen, Datenplattformen sowie Datenr\u00e4ume. Zudem berichtet er regelm\u00e4\u00dfig auf Konferenzen von Ergebnissen aus Forschung und Praxis.\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/author\\\/frank-elberzhager\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft - Blog des Fraunhofer IESE","description":"Im Projekt \u00bbEnStadt:Pfaff\u00ab entwickeln wir L\u00f6sungen f\u00fcr ein nachhaltiges und smartes (Stadt-)Quartier der Zukunft. Diese stellten wir k\u00fcrzlich beim Fachsymposium vor.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/","og_locale":"de_DE","og_type":"article","og_title":"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft - Blog des Fraunhofer IESE","og_description":"Im Projekt \u00bbEnStadt:Pfaff\u00ab entwickeln wir L\u00f6sungen f\u00fcr ein nachhaltiges und smartes (Stadt-)Quartier der Zukunft. Diese stellten wir k\u00fcrzlich beim Fachsymposium vor.","og_url":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/","og_site_name":"Fraunhofer IESE","article_publisher":"https:\/\/www.facebook.com\/FraunhoferIESE\/","article_published_time":"2021-10-21T07:53:59+00:00","article_modified_time":"2024-02-19T10:23:04+00:00","og_image":[{"width":1785,"height":1089,"url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Fachsymposium-Teaserbild.jpg","type":"image\/jpeg"}],"author":"Dr. Frank Elberzhager","twitter_card":"summary_large_image","twitter_creator":"@FraunhoferIESE","twitter_site":"@FraunhoferIESE","twitter_misc":{"Verfasst von":"Dr. Frank Elberzhager","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten","Written by":"Dr. Frank Elberzhager"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/#article","isPartOf":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/"},"author":{"name":"Dr. Frank Elberzhager","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/person\/6ede08c487a56db3656eb7816a65ac9a"},"headline":"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft","datePublished":"2021-10-21T07:53:59+00:00","dateModified":"2024-02-19T10:23:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/"},"wordCount":1309,"publisher":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Fachsymposium-Teaserbild.jpg","keywords":["Digitale \u00d6kosysteme"],"articleSection":["Smart City","Veranstaltung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/","url":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/","name":"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft - Blog des Fraunhofer IESE","isPartOf":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Fachsymposium-Teaserbild.jpg","datePublished":"2021-10-21T07:53:59+00:00","dateModified":"2024-02-19T10:23:04+00:00","description":"Im Projekt \u00bbEnStadt:Pfaff\u00ab entwickeln wir L\u00f6sungen f\u00fcr ein nachhaltiges und smartes (Stadt-)Quartier der Zukunft. Diese stellten wir k\u00fcrzlich beim Fachsymposium vor.","breadcrumb":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/#primaryimage","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Fachsymposium-Teaserbild.jpg","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Fachsymposium-Teaserbild.jpg","width":1785,"height":1089,"caption":"Pfaff Fachsymposium"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/fachsymposium-smartes-quartier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.iese.fraunhofer.de\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bbEnStadt:Pfaff\u00ab-Fachsymposium: Pr\u00e4sentation des aktuellen Projektfortschritts f\u00fcr ein smartes Quartier der Zukunft"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#website","url":"https:\/\/www.iese.fraunhofer.de\/blog\/","name":"Fraunhofer IESE","description":"Blog des Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering","publisher":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.fraunhofer.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization","name":"Fraunhofer IESE","url":"https:\/\/www.iese.fraunhofer.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/fhg_iese_logo.png","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/fhg_iese_logo.png","width":183,"height":50,"caption":"Fraunhofer IESE"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FraunhoferIESE\/","https:\/\/x.com\/FraunhoferIESE","https:\/\/www.linkedin.com\/company\/fraunhoferiese\/","https:\/\/www.youtube.com\/c\/FraunhoferIESE"]},{"@type":"Person","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/person\/6ede08c487a56db3656eb7816a65ac9a","name":"Dr. Frank Elberzhager","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/08\/elberzhager_frank_web-96x96.jpg572de2b19cccbdfa7b2cf475fff214a4","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/08\/elberzhager_frank_web-96x96.jpg","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/08\/elberzhager_frank_web-96x96.jpg","caption":"Dr. Frank Elberzhager"},"description":"Dr. Frank Elberzhager leitet die Abteilung Archicture-Centric Engineering am Fraunhofer IESE. Seit \u00fcber f\u00fcnfzehn Jahren leitet er Forschungs- und Industrieprojekte unterschiedlicher Gr\u00f6\u00dfe und Kritikalit\u00e4t. Inhaltich besch\u00e4ftigt er sich vor allem mit Themen rund um Softwarequalit\u00e4tssicherung und \u2013architektur. Aktueller Fokus seiner Forschungsarbeiten sind \u00d6kosysteme in digitalen Stadtquartieren und l\u00e4ndlichen Regionen, Datenplattformen sowie Datenr\u00e4ume. Zudem berichtet er regelm\u00e4\u00dfig auf Konferenzen von Ergebnissen aus Forschung und Praxis.","url":"https:\/\/www.iese.fraunhofer.de\/blog\/author\/frank-elberzhager\/"}]}},"jetpack_featured_media_url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/10\/Fachsymposium-Teaserbild.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/8561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/comments?post=8561"}],"version-history":[{"count":16,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/8561\/revisions"}],"predecessor-version":[{"id":10111,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/8561\/revisions\/10111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/media\/8564"}],"wp:attachment":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/media?parent=8561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/categories?post=8561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/tags?post=8561"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/coauthors?post=8561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}