{"id":7640,"date":"2021-03-25T08:49:34","date_gmt":"2021-03-25T06:49:34","guid":{"rendered":"https:\/\/www.iese.fraunhofer.de\/blog\/?p=7640"},"modified":"2024-01-12T14:19:05","modified_gmt":"2024-01-12T13:19:05","slug":"rueckblick-2020-agile","status":"publish","type":"post","link":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/","title":{"rendered":"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab"},"content":{"rendered":"<p class=\"lead\">Im Jahr 2020 konnten wir unsere Forschung im Themenbereich \u00bbAgile\u00ab am <a href=\"https:\/\/www.iese.fraunhofer.de\/\">Fraunhofer IESE<\/a> entscheidend vorantreiben. Darum wollen wir in diesem Beitrag nun analog zum <a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2019-unser-agiles-jahr\/\">R\u00fcckblick des letzten Jahres<\/a> die Themen, die wir im Themenfeld \u00bbAgile Software- und Systementwicklung\u00ab in 2020 bearbeitet haben, zusammenfassen und vorstellen. Wir zeigen, welche Themen unsere Expert*innen der Abteilung \u00bbDigital Society Ecosystems\u00ab des Fraunhofer IESE im Jahr 2020 in diversen Projekten und Publikationen bearbeitet haben. Zugleich liefern wir einen umfassenden Ausblick zu aktuellen Trendthemen und Forschungsfragen, welchen wir uns im Jahr 2021 widmen werden.<\/p>\n<h3><strong>Publikationen im Jahr 2020 zum Thema \u00bbAgile\u00ab<\/strong><\/h3>\n<p>In der Abteilung \u00bbDigital Society Ecosystems\u00ab des Fraunhofer IESE blicken wir auf zahlreiche Aktivit\u00e4ten sowie auf die Ver\u00f6ffentlichung unterschiedlicher Forschungsergebnisse und Erkenntnisse in wissenschaftlichen Publikationen, Whitepapern und Blogbeitr\u00e4gen zum Thema \u00bbAgile\u00ab im Jahr 2020 zur\u00fcck. Die folgende Liste bietet einen \u00dcberblick und eine Referenz zu unseren Ver\u00f6ffentlichungen im Jahr 2020:<\/p>\n<ul>\n<li style=\"text-align: left;\"><strong>Januar 2020, LNBIP-Reihe &#8211; Release-Planung<\/strong>: Diese Ver\u00f6ffentlichung erweitert eine bereits 2019 ver\u00f6ffentlichte Umfrage bzgl. der Herausforderungen bei der Release-Planung in einem Umfeld, in dem sich agile und traditionelle Projekte innerhalb eines Produktentwicklungsprozesses abstimmen m\u00fcssen.\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><em>Titel: <a href=\"https:\/\/link.springer.com\/chapter\/10.1007\/978-3-030-37534-8_2\">Release Planning in a Hybrid Project Environment<\/a><\/em><\/li>\n<li><em>Autor*innen: Marner K., Theobald S., Wagner S.<\/em><\/li>\n<li><em>LNBIP-Reihe:<\/em> <em>Advances in Agile and User-Centred Software Engineering<br \/>\n<\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>M\u00e4rz 2020, XP-Konferenz &#8211; Abh\u00e4ngigkeiten agiler Teams in SAFe: <\/strong>Das Scaled Agile Framework (SAFe) bietet eine \u00dcbersicht \u00fcber verschiedene Mechanismen, wie agile Teams mit anderen Unternehmensteilen zusammenarbeiten k\u00f6nnen. Wir haben diese Mechanismen identifiziert und weiteren Forschungsbedarf an der Schnittstelle zwischen agilen Teams und ihrem Umfeld herausgearbeitet.\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><em>Titel: <\/em><a href=\"https:\/\/link.springer.com\/chapter\/10.1007\/978-3-030-58858-8_22\"><em>Dependencies of Agile Teams &#8211; A Review of the Scaled Agile Framework<\/em><br \/>\n<\/a><\/li>\n<li><em>Autor*innen: Theobald S., Schmitt A.<\/em><\/li>\n<li><em><em>Konferenz: Autonomous Agile Teams (Workshop auf der XP2020)<\/em><\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>August 2020, Fraunhofer IESE-Blog &#8211; Projektbericht<\/strong> <strong>Agiles Arbeiten: <\/strong>Wie arbeiten wir eigentlich zur Entwicklung unserer L\u00f6sung zusammen? Ist das agil? Diese Fragen haben wir in diesem Blogbeitrag etwas n\u00e4her beleuchtet. Dazu haben wir unsere Arbeitsweise im Projektteam \u00bbSmart Rural Areas\u00ab mit dem Vorgehen bei Scrum verglichen.\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><em>Titel: <\/em><a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/agiles-arbeiten-im-team\/\"><em>Agiles Arbeiten im Team \u2013 Best-Practice am Beispiel der \u00bbSmart Rural Areas\u00ab<\/em><\/a><\/li>\n<li><em>Autoren: Von Albedyll J.<\/em><\/li>\n<li><em><em>Ver\u00f6ffentlichung: Fraunhofer IESE-Blog<\/em><\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>November 2020, PROFES-Konferenz &#8211;<\/strong>\u00a0<strong>Impediment<\/strong><strong> Management: <\/strong>In seiner Masterarbeit hat sich unser neuer Mitarbeiter Pascal Guckenbiehl damit besch\u00e4ftigt, wie agile Teams Impediments erkennen, dokumentieren, tracken und schlie\u00dflich beseitigen. Die Interviewstudie und das daraus resultierende Modell des Impediment-Management-Prozesses wurden auf der PROFES-Konferenz ver\u00f6ffentlicht.\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><em>Titel:<\/em> <a href=\"https:\/\/link.springer.com\/chapter\/10.1007\/978-3-030-64148-1_4\"><em>Impediment Management of Agile Software Development Teams<\/em><\/a><\/li>\n<li><em>Autoren: Guckenbiehl P., Theobald S.<\/em><\/li>\n<li><em>Konferenz:<\/em> <em><em>21<sup>st<\/sup> International Conference on Product-Focused Software Process Improvement 2020<\/em><\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>November 2020, PROFES-Konferenz &#8211; <\/strong><strong>Agile F\u00fchrung: <\/strong>Die Transition zu einer agilen Organisation ben\u00f6tigt die Unterst\u00fctzung der F\u00fchrungskr\u00e4fte. Wir haben ein systematisches Literaturreview durchgef\u00fchrt, um zu verstehen, wie agile F\u00fchrung und agiles Management abseits von Entwicklungsteams aussieht und dabei z.B. Eigenschaften und Aufgaben von agilen F\u00fchrungskr\u00e4ften identifiziert.\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><em>Titel:<\/em> <a href=\"https:\/\/link.springer.com\/chapter\/10.1007\/978-3-030-64148-1_2\"><em>Agile Leadership and Agile Management on Organizational Level &#8211; A Systematic Literature Review<\/em><\/a><\/li>\n<li><em>Autoren: Theobald S., Prenner N., Krieg A., Schneider K.<\/em><\/li>\n<li><em><em>Konferenz: 21<sup>st<\/sup> International Conference on Product-Focused Software Process Improvement 2020<\/em><\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Dezember 2020, BPM-Journal &#8211; Agile Business Prozesse: <\/strong>Mithilfe einer systematischen Literaturrecherche wurden bestehende Ans\u00e4tze untersucht, die sich damit befassen, inwiefern die agilen Werte und Prinzipien des Agilen Manifests sowie agile Methoden und Praktiken in Gesch\u00e4ftsprozessen angewendet werden k\u00f6nnen. Ziel war es, herauszufinden, ob auch Gesch\u00e4ftsprozesse und nicht nur Software-Entwicklungsprozesse durch den Einsatz von Agilit\u00e4t profitieren und verbessert werden k\u00f6nnen. Das Ergebnis waren 12 Prim\u00e4rquellen, welche anschlie\u00dfend hinsichtlich dreier konkreter Forschungsfragen miteinander verglichen wurden.\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><em>Titel: <\/em><a href=\"https:\/\/link.springer.com\/chapter\/10.1007\/978-3-030-35333-9_52\"><em>Systematic literature review \u2013 improving business processes by implementing agile<\/em><br \/>\n<\/a><\/li>\n<li><em>Autor*innen: Schmitt A., H\u00f6rner S.<br \/>\n<\/em><\/li>\n<li><em><em>Journal: Business Process Management Journal<\/em><\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ul>\n<li><strong>Dezember 2020, Bitkom Arbeitskreis Projektmanagement &#8211;<\/strong>\u00a0<strong>Agilit\u00e4t in Organisationen: <\/strong>Zusammen mit anderen Mitgliedern des Bitkom-Arbeitskreises Projektmanagement wurde \u00fcber das Jahr 2020 hinweg an einem Leitfaden zu diversen Aspekten von Agilit\u00e4t gearbeitet. Unsere Expertise bzgl. agiler Transition und skalierter Agilit\u00e4t wurde in den Leitfaden eingebracht, der kurz vor Jahresabschluss in einer virtuellen Releaseparty ver\u00f6ffentlicht wurde und nun auf der Webseite des Bitkom frei verf\u00fcgbar ist.\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><em>Titel: <\/em><a href=\"https:\/\/www.bitkom.org\/sites\/default\/files\/2020-12\/201124_lf_agilitat-in-organisationen.pdf\"><em>Agilit\u00e4t in Organisationen \u2013 Ein Leitfaden f\u00fcr die Praxis<\/em><br \/>\n<\/a><\/li>\n<li><em>Autor:innen: Schmitt A., Theobald S., Zehler T. &amp; weitere Mitglieder des Bitkom AK Projektmangement<\/em><\/li>\n<li><em>Ver\u00f6ffentlichung: Positionspaper des Bitkom Arbeitskreises Projektmanagement<\/em><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<h3><strong>Unsere Aktivit\u00e4ten zu <\/strong><strong>\u00bbAgile<\/strong><strong>\u00ab<\/strong> <strong>in Industrie- und Forschungsprojekten im Jahr 2020<\/strong><\/h3>\n<p>Neben zahlreichen Publikationen war das Jahr 2020 von vielen weiteren Aktivit\u00e4ten zu Agilit\u00e4t gepr\u00e4gt. Im Folgenden bieten wir einen \u00dcberblick \u00fcber diverse Aktivit\u00e4ten zum Thema \u00bbAgile\u00ab im Rahmen unserer Industrie- und Forschungsprojekte.<\/p>\n<p><strong>Seminar zu \u00bbAgilit\u00e4t im Systems Engineering\u00ab<span style=\"text-decoration: underline;\"><br \/>\n<\/span><\/strong>F\u00fcr einen unserer <a href=\"https:\/\/www.iese.fraunhofer.de\/de\/customers_industries\/referenzprojekt-jamss.html\">Industriekunden<\/a> hielten wir ein dreit\u00e4giges Seminar \u00fcber Agilit\u00e4t im Systems Engineering: Von den Grundlagen, wie dem Agilen Manifest, Scrum und diversen agilen Praktiken, \u00fcber die agile Qualit\u00e4tssicherung und skalierte Agilit\u00e4t (z. B. unter Einsatz des Scaled Agile Frameworks) bis hin zu diversen Diskussionsthemen befassten wir uns mit der Fragestellung, wann agile Vorgehensweisen eingesetzt werden sollen und welche Vorteile der Einsatz bietet. Dabei betrachteten und diskutierten wir m\u00f6gliche Ans\u00e4tze zur Kombination von Agile und Safety Engineering und\/oder der unabh\u00e4ngigen Qualit\u00e4tssicherung.<\/p>\n<p><strong>Forschungsprojekt zu \u00bbAgilit\u00e4t und Safety\u00ab<\/strong><span style=\"text-decoration: underline;\"><br \/>\n<\/span>Im Forschungsprojekt \u00bb<a href=\"https:\/\/www.leistungszentrum-simulation-software.de\/de\/anwendungszentren\/anwenderzentrum--digitale-nutzfahrzeugtechnologie-.html#2\">Neue Erprobungskonzepte f\u00fcr sichere Software in hochautomatisierten Nutzfahrzeugen<\/a>\u00ab bringen wir unsere Expertise dabei ein, die dom\u00e4nenspezifischen Herausforderungen zu ermitteln, die bei der Verbindung von Agilit\u00e4t und Safety-Entwicklungen im Kontext regulatorischer Rahmenbedingungen auftreten. Dazu f\u00fchrten wir neben einer Literaturrecherche auch Workshops mit Expert*innen durch, in denen wir die Erfahrungen aus Forschung und Praxis hinsichtlich der Herausforderungen ermittelten, diskutierten und gruppierten.<\/p>\n<h3><strong>Ausblick: Unsere Forschungsthemen im Jahr 2021<\/strong><\/h3>\n<p>Auch im Jahr 2021 forschen wir flei\u00dfig weiter. Dazu m\u00f6chten wir die im Fokus stehenden Forschungsthemen an dieser Stelle kurz vorstellen.<\/p>\n<p><strong>Agile &amp; Safety<u><br \/>\n<\/u><\/strong>Auch 2021 wird an agilen Entwicklungsans\u00e4tzen im Kontext von sicherheitskritischen Systemen gearbeitet. Aktuell erstellen wir Schulungsunterlagen, um insbesondere KMU die damit einhergehenden Herausforderungen sowie m\u00f6gliche L\u00f6sungsans\u00e4tze n\u00e4herzubringen. Vertiefend wollen wir inkrementelles Safety Engineering untersuchen und aufzeigen, wie dieses mit dem am IESE entwickelten Safety Tool \u00bbSafeTBox\u00ab unterst\u00fctzt werden kann.<\/p>\n<p><strong>Agile Leadership<\/strong><br \/>\nAls Teil des <a href=\"http:\/\/agile-enterprise-survey.de\/\">Forschungsteams zum Themenfeld Agile Organisation<\/a> wollen wir uns 2021 weiter mit dem Thema \u00bbAgile Leadership\u00ab besch\u00e4ftigen. Hierzu erweitern wir die wissenschaftliche Literaturstudie zu agiler F\u00fchrung und agilem Management durch einen Blick auf den aktuellen Stand in der Praxis. Geplant ist ein Workshop mit verschiedenen agilen Expert*innen aus Beratung und Industrie, u. a. zu Fragen wie was agiles Leadership eigentlich bedeutet, welche Eigenschaften eine agile F\u00fchrungskraft mitbringen muss, warum das Thema f\u00fcr die Industrie so relevant ist und wo aktuelle Herausforderungen in der agilen Transformation von F\u00fchrungskr\u00e4ften bestehen.<\/p>\n<p><strong>Agile Verwaltung<\/strong><br \/>\nWir wollen unsere Erfahrungen mit agiler Softwareentwicklung perspektivisch mit der Kernexpertise unserer Abteilung einbringen. Deshalb werden wir uns damit befassen, welche Potenziale agiles Denken und Arbeiten im Bereich der \u00f6ffentlichen Verwaltung sowie im Kontext von digitalen \u00d6kosystemen bieten k\u00f6nnen. Verschiedene agile Praktiken, vor allem aber Ver\u00e4nderungen des Mindsets, k\u00f6nnen helfen, aktuelle Herausforderungen in diesem Bereich zu bew\u00e4ltigen. So kann eine st\u00e4rkere Orientierung an den Bed\u00fcrfnissen der B\u00fcrger*innen erreicht (#OpenGovernment) oder allgemein der Umgang mit der Digitalisierung in Deutschland erleichtert werden. Mithilfe eines Online-Fragebogens sollen der aktuelle Stand und die Potenziale von Digitalisierung und Agilit\u00e4t in \u00f6ffentlichen Verwaltungen identifiziert werden.<\/p>\n<div class=\"info-box\">\n<p>Sie wollen mehr \u00fcber unsere Projekte, Publikationen und Arbeiten rund um das Thema \u00bbAgilit\u00e4t\u00ab erfahren? \u2013 Sprechen Sie uns gerne an! Wir freuen uns \u00fcber jeden Austausch, jedes Feedback und jeden Denkansto\u00df f\u00fcr neue Themen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Kontakt<br \/>\n<\/strong><\/p>\n<p>Sven Theobald<br \/>\nProject Manager<br \/>\nDept. Digital Society Ecosystems<\/p>\n<p><a href=\"mailto:sven.theobald@iese.fraunhofer.de\">sven.theobald@iese.fraunhofer.de<\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im Jahr 2020 konnten wir unsere Forschung im Themenbereich \u00bbAgile\u00ab am Fraunhofer IESE entscheidend vorantreiben. Darum wollen wir in diesem Beitrag nun analog zum R\u00fcckblick des letzten Jahres die Themen, die wir im Themenfeld \u00bbAgile Software- und Systementwicklung\u00ab in 2020&#8230;<\/p>\n","protected":false},"author":91,"featured_media":7682,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[211],"tags":[235,411],"coauthors":[385,66,413,345],"class_list":["post-7640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digitale-transformation","tag-agile","tag-agile-organisation"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab - Blog des Fraunhofer IESE<\/title>\n<meta name=\"description\" content=\"Im Jahr 2020 gelang es, die Forschung des Fraunhofer IESE zu Agile entscheidend vorantreiben. Dar\u00fcber berichten wir im Fraunhofer IESE-Blog.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab - Blog des Fraunhofer IESE\" \/>\n<meta property=\"og:description\" content=\"Im Jahr 2020 gelang es, die Forschung des Fraunhofer IESE zu Agile entscheidend vorantreiben. Dar\u00fcber berichten wir im Fraunhofer IESE-Blog.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/\" \/>\n<meta property=\"og:site_name\" content=\"Fraunhofer IESE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FraunhoferIESE\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-25T06:49:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-12T13:19:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/03\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1304\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sven Theobald, Anna Theobald, Pascal Guckenbiehl, Jannis von Albedyll\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FraunhoferIESE\" \/>\n<meta name=\"twitter:site\" content=\"@FraunhoferIESE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sven Theobald\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Sven Theobald, Anna Theobald, Pascal Guckenbiehl, Jannis von Albedyll\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/\"},\"author\":{\"name\":\"Sven Theobald\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/person\\\/19ec7ab42cf2e07e34f7b2d654af5c7e\"},\"headline\":\"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab\",\"datePublished\":\"2021-03-25T06:49:34+00:00\",\"dateModified\":\"2024-01-12T13:19:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/\"},\"wordCount\":1267,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png\",\"keywords\":[\"Agile\",\"Agile Organisation\"],\"articleSection\":[\"Digitale Transformation\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/\",\"name\":\"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab - Blog des Fraunhofer IESE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png\",\"datePublished\":\"2021-03-25T06:49:34+00:00\",\"dateModified\":\"2024-01-12T13:19:05+00:00\",\"description\":\"Im Jahr 2020 gelang es, die Forschung des Fraunhofer IESE zu Agile entscheidend vorantreiben. Dar\u00fcber berichten wir im Fraunhofer IESE-Blog.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png\",\"width\":1304,\"height\":610,\"caption\":\"R\u00fcckblick: Agiles Jahr 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/rueckblick-2020-agile\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\",\"name\":\"Fraunhofer IESE\",\"description\":\"Blog des Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\",\"name\":\"Fraunhofer IESE\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/fhg_iese_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/fhg_iese_logo.png\",\"width\":183,\"height\":50,\"caption\":\"Fraunhofer IESE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FraunhoferIESE\\\/\",\"https:\\\/\\\/x.com\\\/FraunhoferIESE\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fraunhoferiese\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/FraunhoferIESE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/person\\\/19ec7ab42cf2e07e34f7b2d654af5c7e\",\"name\":\"Sven Theobald\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/sven_theobald_C97A0366_web-96x96.jpg9b2128361eca86c9f5c7118a2cb3e1e1\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/sven_theobald_C97A0366_web-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/sven_theobald_C97A0366_web-96x96.jpg\",\"caption\":\"Sven Theobald\"},\"description\":\"Sven Theobald arbeitet seit 2016 als wissenschaftlicher Mitarbeiter am Fraunhofer IESE in Kaiserslautern. In der Vergangenheit besch\u00e4ftigte er sich mit der Verbesserung von Entwicklungsprozessen, insbesondere mithilfe agiler Entwicklung. Um Agilit\u00e4t in einem regulierten Umfeld einsetzen zu k\u00f6nnen, untersuchte er die Vor- und Nachteile einzelner agiler Praktiken, um diese ggf. angepasst schrittweise in bestehende Prozesse einbinden zu k\u00f6nnen. Als Projektleiter und zertifizierter Scrum Master f\u00fchrt er in Industrieprojekten Schulungen und Workshops durch und ber\u00e4t Unternehmen dabei, die passende Agilit\u00e4t f\u00fcr ihren Kontext zu finden. Seine Forschung besch\u00e4ftigt sich mit agilen Reifegradmodellen und skalierter Agilit\u00e4t bis hin zur agilen Organisation. In seinem Promotionsthema behandelt er die Einbindung agiler Teams in nicht-agile Unternehmen, insbesondere im Umfeld der Systementwicklung. Als Sprecher auf Konferenzen sucht er regelm\u00e4\u00dfig den Austausch mit der agilen Community.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sven-theobald\\\/\"],\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/author\\\/sven-theobald\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab - Blog des Fraunhofer IESE","description":"Im Jahr 2020 gelang es, die Forschung des Fraunhofer IESE zu Agile entscheidend vorantreiben. Dar\u00fcber berichten wir im Fraunhofer IESE-Blog.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/","og_locale":"de_DE","og_type":"article","og_title":"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab - Blog des Fraunhofer IESE","og_description":"Im Jahr 2020 gelang es, die Forschung des Fraunhofer IESE zu Agile entscheidend vorantreiben. Dar\u00fcber berichten wir im Fraunhofer IESE-Blog.","og_url":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/","og_site_name":"Fraunhofer IESE","article_publisher":"https:\/\/www.facebook.com\/FraunhoferIESE\/","article_published_time":"2021-03-25T06:49:34+00:00","article_modified_time":"2024-01-12T13:19:05+00:00","og_image":[{"width":1304,"height":610,"url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/03\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png","type":"image\/png"}],"author":"Sven Theobald, Anna Theobald, Pascal Guckenbiehl, Jannis von Albedyll","twitter_card":"summary_large_image","twitter_creator":"@FraunhoferIESE","twitter_site":"@FraunhoferIESE","twitter_misc":{"Verfasst von":"Sven Theobald","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten","Written by":"Sven Theobald, Anna Theobald, Pascal Guckenbiehl, Jannis von Albedyll"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/#article","isPartOf":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/"},"author":{"name":"Sven Theobald","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/person\/19ec7ab42cf2e07e34f7b2d654af5c7e"},"headline":"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab","datePublished":"2021-03-25T06:49:34+00:00","dateModified":"2024-01-12T13:19:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/"},"wordCount":1267,"publisher":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/03\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png","keywords":["Agile","Agile Organisation"],"articleSection":["Digitale Transformation"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/","url":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/","name":"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab - Blog des Fraunhofer IESE","isPartOf":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/03\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png","datePublished":"2021-03-25T06:49:34+00:00","dateModified":"2024-01-12T13:19:05+00:00","description":"Im Jahr 2020 gelang es, die Forschung des Fraunhofer IESE zu Agile entscheidend vorantreiben. Dar\u00fcber berichten wir im Fraunhofer IESE-Blog.","breadcrumb":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/#primaryimage","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/03\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/03\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png","width":1304,"height":610,"caption":"R\u00fcckblick: Agiles Jahr 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/rueckblick-2020-agile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.iese.fraunhofer.de\/blog\/"},{"@type":"ListItem","position":2,"name":"R\u00fcckblick 2020: Unsere Forschung im Themenbereich \u00bbAgile\u00ab"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#website","url":"https:\/\/www.iese.fraunhofer.de\/blog\/","name":"Fraunhofer IESE","description":"Blog des Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering","publisher":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.fraunhofer.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization","name":"Fraunhofer IESE","url":"https:\/\/www.iese.fraunhofer.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/fhg_iese_logo.png","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/fhg_iese_logo.png","width":183,"height":50,"caption":"Fraunhofer IESE"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FraunhoferIESE\/","https:\/\/x.com\/FraunhoferIESE","https:\/\/www.linkedin.com\/company\/fraunhoferiese\/","https:\/\/www.youtube.com\/c\/FraunhoferIESE"]},{"@type":"Person","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/person\/19ec7ab42cf2e07e34f7b2d654af5c7e","name":"Sven Theobald","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2024\/05\/sven_theobald_C97A0366_web-96x96.jpg9b2128361eca86c9f5c7118a2cb3e1e1","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2024\/05\/sven_theobald_C97A0366_web-96x96.jpg","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2024\/05\/sven_theobald_C97A0366_web-96x96.jpg","caption":"Sven Theobald"},"description":"Sven Theobald arbeitet seit 2016 als wissenschaftlicher Mitarbeiter am Fraunhofer IESE in Kaiserslautern. In der Vergangenheit besch\u00e4ftigte er sich mit der Verbesserung von Entwicklungsprozessen, insbesondere mithilfe agiler Entwicklung. Um Agilit\u00e4t in einem regulierten Umfeld einsetzen zu k\u00f6nnen, untersuchte er die Vor- und Nachteile einzelner agiler Praktiken, um diese ggf. angepasst schrittweise in bestehende Prozesse einbinden zu k\u00f6nnen. Als Projektleiter und zertifizierter Scrum Master f\u00fchrt er in Industrieprojekten Schulungen und Workshops durch und ber\u00e4t Unternehmen dabei, die passende Agilit\u00e4t f\u00fcr ihren Kontext zu finden. Seine Forschung besch\u00e4ftigt sich mit agilen Reifegradmodellen und skalierter Agilit\u00e4t bis hin zur agilen Organisation. In seinem Promotionsthema behandelt er die Einbindung agiler Teams in nicht-agile Unternehmen, insbesondere im Umfeld der Systementwicklung. Als Sprecher auf Konferenzen sucht er regelm\u00e4\u00dfig den Austausch mit der agilen Community.","sameAs":["https:\/\/www.linkedin.com\/in\/sven-theobald\/"],"url":"https:\/\/www.iese.fraunhofer.de\/blog\/author\/sven-theobald\/"}]}},"jetpack_featured_media_url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2021\/03\/2021-03-23_Bild-zu-Rueckblick-2020-Agile.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/7640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/users\/91"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/comments?post=7640"}],"version-history":[{"count":36,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/7640\/revisions"}],"predecessor-version":[{"id":11320,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/7640\/revisions\/11320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/media\/7682"}],"wp:attachment":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/media?parent=7640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/categories?post=7640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/tags?post=7640"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/coauthors?post=7640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}