{"id":3666,"date":"2019-07-03T21:52:31","date_gmt":"2019-07-03T19:52:31","guid":{"rendered":"https:\/\/blog.iese.fraunhofer.de\/?p=3666"},"modified":"2024-01-22T13:12:36","modified_gmt":"2024-01-22T12:12:36","slug":"schnittstelle-zwischen-requirements-engineering-und-testing","status":"publish","type":"post","link":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/","title":{"rendered":"Test!t Fachtag: An der Schnittstelle zwischen Requirements Engineering und Testing"},"content":{"rendered":"<p class=\"lead\">Am 18. Juni 2019 fand der 2. test!t Fachtag in der schleswig-holsteinischen Landeshauptstadt Kiel statt. <a href=\"https:\/\/www.iese.fraunhofer.de\/blog\/author\/eddy-groen\/\" target=\"_blank\" rel=\"noopener noreferrer\">Eduard C. Groen<\/a> vom Fraunhofer IESE war als Referent und Workshopleiter zu den Themen Digitale Transformation und Requirements Engineering eingeladen und berichtet zum Tag.<\/p>\n<p>Der <a href=\"https:\/\/www.testit-fachtag.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">test!t Fachtag<\/a> wurde vom Engineering-Dienstleister <a href=\"https:\/\/scope-engineering.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Scope Engineering GmbH<\/a> als Austauschplattform f\u00fcr seine Kunden und interessierte Akteure ins Leben gerufen. Hiermit wurde ein langj\u00e4hriger Wunsch erf\u00fcllt: ein Fachtag f\u00fcr Praktiker in Norddeutschland und insbesondere in Schleswig-Holstein, damit diese nicht mehr von zuf\u00e4lligen Begegnungen auf Tagungen in Berlin, M\u00fcnchen oder anderswo abh\u00e4ngig sind, um sich untereinander zu vernetzen.<\/p>\n<p>Zu den Anwesenden z\u00e4hlten u.a. Firmen aus dem Medizinbereich, wie z.B. ein Ger\u00e4tehersteller aus Hamburg sowie eine L\u00fcbecker Software-Entwicklungsfirma. Dar\u00fcber hinaus waren Dienstleister aus den Bereichen Komponententests, Telekommunikation und Fulfillment sowie Vertreter von Stadtwerken vertreten. Der Fachtag sollte diese Personen nicht nur vernetzen, sondern ihnen auch neue Anregungen mitgeben und das gegenseitige Verst\u00e4ndnis zwischen Requirements Engineers und Testern vertiefen.<\/p>\n<p>Am Vormittag stand das <a href=\"https:\/\/www.iese.fraunhofer.de\/de\/leistungen\/requirements-engineering.html\" target=\"_blank\" rel=\"noopener noreferrer\">Requirements Engineering<\/a> im Fokus. Die Er\u00f6ffnungskeynote von Eduard C. Groen war als Impulsvortrag konzipiert und trug den Titel <a href=\"https:\/\/www.testit-fachtag.de\/referenten\" target=\"_blank\" rel=\"noopener noreferrer\">\u00bbDie Digitale Transformation trifft jeden und alles\u2026 auch Ihr Requirements Engineering\u00ab<\/a>. Mit zahlreichen Beispielen aus den Erfahrungen des Fraunhofer IESE, mitunter aus traditionelleren Dom\u00e4nen wie der Automobilindustrie (<a href=\"https:\/\/www.iese.fraunhofer.de\/de\/customers_industries\/success-story-caruso.html\" target=\"_blank\" rel=\"noopener noreferrer\">Caruso<\/a>, PRO-OPT) und dem Rechnungswesen, wurden die einzigartigen Chancen der Digitalen Transformation skizziert und Erfahrungen mit der Durchf\u00fchrung von <a href=\"http:\/\/publica.fraunhofer.de\/dokumente\/N-534973.html\" target=\"_blank\" rel=\"noopener noreferrer\">Requirements Engineering in solchen Projekten<\/a> beschrieben.<\/p>\n<h3>Im Workshop \u00fcbten sich die Teilnehmer im Requirements Engineering und der Ableitung von Testf\u00e4llen<\/h3>\n<p>Die Kompetenz der Teilnehmer zeigte sich sehr deutlich in der Zusammenarbeit bei der Umsetzung einer bewusst etwas verwirrenden Auflistung von Kundenw\u00fcnschen f\u00fcr ein \u00bbGef\u00e4\u00df f\u00fcr Fl\u00fcssigkeiten\u00ab in gute Anforderungen. Hierzu durften zum Gl\u00fcck auch Kl\u00e4rungsgespr\u00e4che mit der Kundin gef\u00fchrt werden, um daraus Anforderungen f\u00fcr eine innovative Tasse abzuleiten. Bei dieser Anforderungsspezifikation wurden Schreibregeln bereits gut eingehalten, funktionale von nichtfunktionalen Anforderungen getrennt, und die Anforderungen m\u00f6glichst l\u00f6sungsfrei formuliert, was der Qualit\u00e4t zugutekam.<\/p>\n<p>Nach einem schmackhaften Mittagessen stand das Testen im Zentrum. Die erarbeiteten Anforderungen sowie einige Personen wurden zwischen den beiden Gruppen ausgetauscht. Beide Gruppen kamen zu einem interessanten Schluss: Die Anforderungen wiesen h\u00e4ufig Unklarheiten auf, wenn man daraus Testf\u00e4lle abzuleiten versuchte. Eine professionelle Zeichnerin erhielt die Aufgabe, basierend auf den Anforderungen eine visuelle Darstellung des Produkts zu erzeugen.<\/p>\n<figure id=\"attachment_3678\" aria-describedby=\"caption-attachment-3678\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3678 size-full\" src=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_ergebnis1u2.jpg\" alt=\"Fraunhofer IESE - Entwurfsergebnisse des Requirements Engineering und Testing Workshops\" width=\"610\" height=\"400\" srcset=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_ergebnis1u2.jpg 610w, https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_ergebnis1u2-400x262.jpg 400w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><figcaption id=\"caption-attachment-3678\" class=\"wp-caption-text\">Innovative Tassen: Zwei visualisierte Entwurfsergebnisse<\/figcaption><\/figure>\n<p>\u00dcberraschenderweise waren die Unklarheiten, die ihre Aufgabe erschwerten, oftmals genau die gleichen, die bei der Spezifikation von Testf\u00e4llen f\u00fcr Probleme sorgten. Weil die Anforderungen dar\u00fcber hinaus l\u00f6sungsfrei geschrieben wurden, musste sie an mehreren Stellen eigenst\u00e4ndig Entwurfsentscheidungen treffen.<\/p>\n<h3>Wichtigkeit der Kommunikation zwischen Kunde, Requirements Engineer, Tester und Umsetzer<\/h3>\n<p>Die \u00dcbung war \u00fcberraschend simpel; die Umsetzung war f\u00fcr die erfahrenen Tester und Requirements Engineers jedoch keineswegs augenscheinlich. Gerade deswegen wurde offensichtlich: je mehr die Kundin, die Requirements Engineers, die Tester und die Ersteller von Prototypen zusammenarbeiten und kommunizieren, desto besser wird das Ergebnis. Diese Erfahrungen hat das Fraunhofer IESE auch bei der Erstellung <a href=\"https:\/\/www.iese.fraunhofer.de\/de\/leistungen\/requirements-engineering.html\" target=\"_blank\" rel=\"noopener noreferrer\">innovativer Produkte und Dienstleistungen<\/a> gemacht.<\/p>\n<p>Am Ende des Tages folgten noch zwei weitere Keynotes zur Inspiration. Axel Giernas von Scope Engineering GmbH \u00fcberzeugte die Teilnehmer mit seinem beispielhaften Durchlauf eines Projekts von der Notwendigkeit eines einheitlichen Testmanagements. Dadurch werden akute Fehler im Testing, wie Mangel an Vorbereitung, Testdaten, Testumgebungsmanagement, Testautomatisierung sowie notwendigem Know-how, erfolgreich vermieden. Zum Abschluss gab Georg Haupt von der oose Innovative Informatik eG praktische Tipps zur Bew\u00e4ltigung gro\u00dfer Mengen an Testf\u00e4llen durch selbstorganisierte Teams, mit effizienten Methoden zur Aufgabenverteilung und Konsenzbildung.<\/p>\n<p>Die Ziele des Fachtags wurden \u00fcbertroffen\u00a0und damit war der test!it eine wertvolle Veranstaltung f\u00fcr alle Teilnehmer. Trotz des bereits hohen Niveaus der Informatik in Schleswig-Holstein bieten die pr\u00e4sentierten Anregungen f\u00fcr Qualit\u00e4tsverbesserungen und die vorgeschlagenen Schritte zur Digitalen Transformation sicherlich Impulse f\u00fcr weitere Innovationen.<\/p>\n<p>Nachsatz: Ein Interview mit <a href=\"https:\/\/twitter.com\/GeraldSwarat\" target=\"_blank\" rel=\"noopener noreferrer\">Gerald Swarat<\/a> vom Fraunhofer IESE zum Thema Digitalisierung ist auf der Website von <a href=\"https:\/\/www.kielregion.de\/wirtschaft\/digitalisierung\/\" target=\"_blank\" rel=\"noopener noreferrer\">KielRegion<\/a> zu finden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am 18. Juni 2019 fand der 2. test!t Fachtag in der schleswig-holsteinischen Landeshauptstadt Kiel statt. Eduard C. Groen vom Fraunhofer IESE war als Referent und Workshopleiter zu den Themen Digitale Transformation und Requirements Engineering eingeladen und berichtet zum Tag. Der&#8230;<\/p>\n","protected":false},"author":46,"featured_media":3675,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[211,13],"tags":[127],"coauthors":[80],"class_list":["post-3666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digitale-transformation","category-veranstaltung","tag-requirements-engineering"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fachtag Test!t: Requirements Engineering und Testing - Blog des Fraunhofer IESE<\/title>\n<meta name=\"description\" content=\"Eduard C. Groen vom Fraunhofer IESE referierte auf der Test!t und f\u00fchrte einen Workshop durch zu Requirements Engineering und Testing.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fachtag Test!t: Requirements Engineering und Testing - Blog des Fraunhofer IESE\" \/>\n<meta property=\"og:description\" content=\"Eduard C. Groen vom Fraunhofer IESE referierte auf der Test!t und f\u00fchrte einen Workshop durch zu Requirements Engineering und Testing.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/\" \/>\n<meta property=\"og:site_name\" content=\"Fraunhofer IESE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/FraunhoferIESE\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-03T19:52:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T12:12:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"748\" \/>\n\t<meta property=\"og:image:height\" content=\"375\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dr. Eddy Groen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@FraunhoferIESE\" \/>\n<meta name=\"twitter:site\" content=\"@FraunhoferIESE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Eddy Groen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Dr. Eddy Groen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/\"},\"author\":{\"name\":\"Dr. Eddy Groen\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/person\\\/b184e099b02c6e1e095b3ed382561ecb\"},\"headline\":\"Test!t Fachtag: An der Schnittstelle zwischen Requirements Engineering und Testing\",\"datePublished\":\"2019-07-03T19:52:31+00:00\",\"dateModified\":\"2024-01-22T12:12:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/\"},\"wordCount\":689,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg\",\"keywords\":[\"Requirements Engineering\"],\"articleSection\":[\"Digitale Transformation\",\"Veranstaltung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/\",\"name\":\"Fachtag Test!t: Requirements Engineering und Testing - Blog des Fraunhofer IESE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg\",\"datePublished\":\"2019-07-03T19:52:31+00:00\",\"dateModified\":\"2024-01-22T12:12:36+00:00\",\"description\":\"Eduard C. Groen vom Fraunhofer IESE referierte auf der Test!t und f\u00fchrte einen Workshop durch zu Requirements Engineering und Testing.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg\",\"width\":748,\"height\":375,\"caption\":\"Eddy Groen leitet Workshop zur Anforderungsspezifikation (Requirements Engineering)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/schnittstelle-zwischen-requirements-engineering-und-testing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Test!t Fachtag: An der Schnittstelle zwischen Requirements Engineering und Testing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\",\"name\":\"Fraunhofer IESE\",\"description\":\"Blog des Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#organization\",\"name\":\"Fraunhofer IESE\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/fhg_iese_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/fhg_iese_logo.png\",\"width\":183,\"height\":50,\"caption\":\"Fraunhofer IESE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/FraunhoferIESE\\\/\",\"https:\\\/\\\/x.com\\\/FraunhoferIESE\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fraunhoferiese\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/FraunhoferIESE\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/#\\\/schema\\\/person\\\/b184e099b02c6e1e095b3ed382561ecb\",\"name\":\"Dr. Eddy Groen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/eddy_groen_C97A0141_web-96x96.jpgf5109aab11ebae41dacba69a72f8164f\",\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/eddy_groen_C97A0141_web-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/eddy_groen_C97A0141_web-96x96.jpg\",\"caption\":\"Dr. Eddy Groen\"},\"description\":\"Dr. Eduard C. Groen ist Senior Requirements Engineer &amp; Projektleiter am Fraunhofer IESE und er koordiniert die Digitale Nachhaltigkeit. Seine Arbeit ist dom\u00e4nen\u00fcbergreifend und fokussiert sich auf das Digital Design komplexer Systeme (z. B. digitale \u00d6kosysteme oder das Internet of Things) und darauf, wie diese die Herausforderungen der Nachhaltigkeit bew\u00e4ltigen k\u00f6nnen. Neben beratenden T\u00e4tigkeiten in der Industrie \u00fcbernahm er u. a. leitende Funktionen in der Beratung von Bundesministerien zu digitalen Datenplattformen f\u00fcr die Landwirtschaft (BMEL), in der Weiterentwicklung der Forschung zu dynamischen Systems-of-Systems (\u00bbDynaSoS\u00ab; BMBF) sowie in Projekten im Bereich Usable Security &amp; Privacy (\u00bbTrUSD\u00ab, \u00bbD\u2018accord\u00ab). Am Fraunhofer IESE ist er seit \u00fcber 10 Jahren Themenverantwortlicher f\u00fcr \u00bbCrowd-Based Requirements Engineering\u00ab. Neben seiner Arbeit am Fraunhofer IESE ist er beim International Requirements Engineering Board (IREB) Leiter der Special Interest Group on Sustainability. Er hat ein Master in der Psychologie von der Universit\u00e4t Twente und absolvierte 2025 seine Doktorarbeit an der Universit\u00e4t Utrecht, betreut von Prof. Dr. Sjaak Brinkkemper, Prof. Dr. Fabiano Dalpiaz und Prof. Dr.-Ing. J\u00f6rg D\u00f6rr. Als Wissenschaftler decken seine \u00fcber 25 Publikationen Themen wie Qualit\u00e4tsanforderungen, Nutzerfeedbackklassifikation, Digitale \u00d6kosysteme, gebrauchstauglicher Datenschutz, IoT und Nachhaltigkeit ab. Er ist u.a. Mitglied in den Hauptprogrammkomitees der Konferenzen REFSQ und RE, leitet den Industry-Innovation-Track der RE\u201926, leitete den Posters- und Tools-Track der REFSQ\u201920 und den Workshops-Track der REFSQ\u201925 und erhielt den Best Reviewer Award der REFSQ\u201923.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/eddygroen\\\/\"],\"url\":\"https:\\\/\\\/www.iese.fraunhofer.de\\\/blog\\\/author\\\/eddy-groen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fachtag Test!t: Requirements Engineering und Testing - Blog des Fraunhofer IESE","description":"Eduard C. Groen vom Fraunhofer IESE referierte auf der Test!t und f\u00fchrte einen Workshop durch zu Requirements Engineering und Testing.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/","og_locale":"de_DE","og_type":"article","og_title":"Fachtag Test!t: Requirements Engineering und Testing - Blog des Fraunhofer IESE","og_description":"Eduard C. Groen vom Fraunhofer IESE referierte auf der Test!t und f\u00fchrte einen Workshop durch zu Requirements Engineering und Testing.","og_url":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/","og_site_name":"Fraunhofer IESE","article_publisher":"https:\/\/www.facebook.com\/FraunhoferIESE\/","article_published_time":"2019-07-03T19:52:31+00:00","article_modified_time":"2024-01-22T12:12:36+00:00","og_image":[{"width":748,"height":375,"url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg","type":"image\/jpeg"}],"author":"Dr. Eddy Groen","twitter_card":"summary_large_image","twitter_creator":"@FraunhoferIESE","twitter_site":"@FraunhoferIESE","twitter_misc":{"Verfasst von":"Dr. Eddy Groen","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten","Written by":"Dr. Eddy Groen"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/#article","isPartOf":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/"},"author":{"name":"Dr. Eddy Groen","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/person\/b184e099b02c6e1e095b3ed382561ecb"},"headline":"Test!t Fachtag: An der Schnittstelle zwischen Requirements Engineering und Testing","datePublished":"2019-07-03T19:52:31+00:00","dateModified":"2024-01-22T12:12:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/"},"wordCount":689,"publisher":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg","keywords":["Requirements Engineering"],"articleSection":["Digitale Transformation","Veranstaltung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/","url":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/","name":"Fachtag Test!t: Requirements Engineering und Testing - Blog des Fraunhofer IESE","isPartOf":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/#primaryimage"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg","datePublished":"2019-07-03T19:52:31+00:00","dateModified":"2024-01-22T12:12:36+00:00","description":"Eduard C. Groen vom Fraunhofer IESE referierte auf der Test!t und f\u00fchrte einen Workshop durch zu Requirements Engineering und Testing.","breadcrumb":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/#primaryimage","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg","width":748,"height":375,"caption":"Eddy Groen leitet Workshop zur Anforderungsspezifikation (Requirements Engineering)"},{"@type":"BreadcrumbList","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/schnittstelle-zwischen-requirements-engineering-und-testing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.iese.fraunhofer.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Test!t Fachtag: An der Schnittstelle zwischen Requirements Engineering und Testing"}]},{"@type":"WebSite","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#website","url":"https:\/\/www.iese.fraunhofer.de\/blog\/","name":"Fraunhofer IESE","description":"Blog des Fraunhofer-Institut f\u00fcr Experimentelles Software Engineering","publisher":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iese.fraunhofer.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#organization","name":"Fraunhofer IESE","url":"https:\/\/www.iese.fraunhofer.de\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/fhg_iese_logo.png","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2016\/08\/fhg_iese_logo.png","width":183,"height":50,"caption":"Fraunhofer IESE"},"image":{"@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/FraunhoferIESE\/","https:\/\/x.com\/FraunhoferIESE","https:\/\/www.linkedin.com\/company\/fraunhoferiese\/","https:\/\/www.youtube.com\/c\/FraunhoferIESE"]},{"@type":"Person","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/#\/schema\/person\/b184e099b02c6e1e095b3ed382561ecb","name":"Dr. Eddy Groen","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2024\/07\/eddy_groen_C97A0141_web-96x96.jpgf5109aab11ebae41dacba69a72f8164f","url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2024\/07\/eddy_groen_C97A0141_web-96x96.jpg","contentUrl":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2024\/07\/eddy_groen_C97A0141_web-96x96.jpg","caption":"Dr. Eddy Groen"},"description":"Dr. Eduard C. Groen ist Senior Requirements Engineer &amp; Projektleiter am Fraunhofer IESE und er koordiniert die Digitale Nachhaltigkeit. Seine Arbeit ist dom\u00e4nen\u00fcbergreifend und fokussiert sich auf das Digital Design komplexer Systeme (z. B. digitale \u00d6kosysteme oder das Internet of Things) und darauf, wie diese die Herausforderungen der Nachhaltigkeit bew\u00e4ltigen k\u00f6nnen. Neben beratenden T\u00e4tigkeiten in der Industrie \u00fcbernahm er u. a. leitende Funktionen in der Beratung von Bundesministerien zu digitalen Datenplattformen f\u00fcr die Landwirtschaft (BMEL), in der Weiterentwicklung der Forschung zu dynamischen Systems-of-Systems (\u00bbDynaSoS\u00ab; BMBF) sowie in Projekten im Bereich Usable Security &amp; Privacy (\u00bbTrUSD\u00ab, \u00bbD\u2018accord\u00ab). Am Fraunhofer IESE ist er seit \u00fcber 10 Jahren Themenverantwortlicher f\u00fcr \u00bbCrowd-Based Requirements Engineering\u00ab. Neben seiner Arbeit am Fraunhofer IESE ist er beim International Requirements Engineering Board (IREB) Leiter der Special Interest Group on Sustainability. Er hat ein Master in der Psychologie von der Universit\u00e4t Twente und absolvierte 2025 seine Doktorarbeit an der Universit\u00e4t Utrecht, betreut von Prof. Dr. Sjaak Brinkkemper, Prof. Dr. Fabiano Dalpiaz und Prof. Dr.-Ing. J\u00f6rg D\u00f6rr. Als Wissenschaftler decken seine \u00fcber 25 Publikationen Themen wie Qualit\u00e4tsanforderungen, Nutzerfeedbackklassifikation, Digitale \u00d6kosysteme, gebrauchstauglicher Datenschutz, IoT und Nachhaltigkeit ab. Er ist u.a. Mitglied in den Hauptprogrammkomitees der Konferenzen REFSQ und RE, leitet den Industry-Innovation-Track der RE\u201926, leitete den Posters- und Tools-Track der REFSQ\u201920 und den Workshops-Track der REFSQ\u201925 und erhielt den Best Reviewer Award der REFSQ\u201923.","sameAs":["https:\/\/www.linkedin.com\/in\/eddygroen\/"],"url":"https:\/\/www.iese.fraunhofer.de\/blog\/author\/eddy-groen\/"}]}},"jetpack_featured_media_url":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-content\/uploads\/2019\/07\/2019_fraunhoferIESE_groen_workshop_testit_header.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/3666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/comments?post=3666"}],"version-history":[{"count":18,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/3666\/revisions"}],"predecessor-version":[{"id":10975,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/posts\/3666\/revisions\/10975"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/media\/3675"}],"wp:attachment":[{"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/media?parent=3666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/categories?post=3666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/tags?post=3666"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.iese.fraunhofer.de\/blog\/wp-json\/wp\/v2\/coauthors?post=3666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}